{"id":24424,"date":"2024-05-20T17:18:25","date_gmt":"2024-05-20T15:18:25","guid":{"rendered":"https:\/\/www.cgjung.net\/espace\/?page_id=24424"},"modified":"2026-06-07T14:14:50","modified_gmt":"2026-06-07T12:14:50","slug":"parfaite-compagne","status":"publish","type":"page","link":"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/parfaite-compagne\/","title":{"rendered":"Tenir la tension du transfert \u00e9rotique : incarner le Capitaine Picard dans \u00ab\u00a0La Parfaite Compagne\u00a0\u00bb de Star Trek"},"content":{"rendered":"<p><strong>Peggy Vermeesch explore la mani\u00e8re dont un th\u00e9rapeute peut accompagner un patient dont la gu\u00e9rison et la transformation d\u00e9pendent de la possibilit\u00e9 de (re)vivre l&rsquo;exp\u00e9rience d&rsquo;un premier amour parental sain. <\/strong><\/p>\n<p>Le mythe de Star Trek lui sert de fil conducteur. En plus de bonnes limites, il est crucial d&rsquo;appr\u00e9cier et d&rsquo;aimer v\u00e9ritablement nos patients lorsque la coniunctio est constell\u00e9e.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24375\" src=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/04\/ST-TNG_The_Perfect_Mate.jpg\" alt=\"\" width=\"600\" height=\"453\" srcset=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/04\/ST-TNG_The_Perfect_Mate.jpg 600w, https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/04\/ST-TNG_The_Perfect_Mate-300x227.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.cgjung.net\/espace\/jps\/articles\/peggy-vermeesch\/perfect-mate\/\">Version anglaise de cet article<\/a><\/p>\n<p>J&rsquo;explore les mythes qui entourent la sexualit\u00e9 et le danger d&rsquo;abus et de pr\u00e9judices \u00e0 long terme dans un processus de maturation perturb\u00e9. Je souligne l\u2019in\u00e9galit\u00e9 en mati\u00e8re d\u2019empathie et de protection soci\u00e9tales pour les hommes. En utilisant les th\u00e9ories de Rutter (1989), j&rsquo;analyse \u00e0 la fois le potentiel et le danger des \u00ab\u00a0relations en zone interdite\u00a0\u00bb.<\/p>\n<h2><strong>Sur cette page<\/strong><\/h2>\n<ul>\n<li><a href=\"#preambule\">Pr\u00e9ambule<\/a><\/li>\n<li><a href=\"#promesse\">La Promesse de la Zone Interdite<\/a><br \/>\nTransfert et contre-transfert \u00e9rotiques | Hommes, femmes et personnes non-binaires.<\/li>\n<li><a href=\"#mate\">La Parfaite Compagne de Star Trek<\/a><br \/>\n\u00c9veil sexuel | Le mythe masculin du f\u00e9minin | La compassion exploit\u00e9e | Doubles standards.<\/li>\n<li><a href=\"#transference\">Amour de transfert<\/a><br \/>\nTransfert personnel et arch\u00e9typal |&nbsp;L&rsquo;art d&rsquo;appr\u00e9cier nos patients&nbsp;| Tenir la limite.<\/li>\n<li><a href=\"#coniunctio\">Coniunctio<\/a><br \/>\nLe Trickster au service du Soi | Amiti\u00e9 symbolique | L&rsquo;union transformatrice | Les limites du lien th\u00e9rapeutique.<\/li>\n<li><a href=\"#society\">Le r\u00f4le de la soci\u00e9t\u00e9<\/a><\/li>\n<\/ul>\n<h1 style=\"text-align: center;\"><strong>PREAMBULE<\/strong><a id=\"preambule\"><\/a><\/h1>\n<p>L&rsquo;\u00e9pisode de \u00ab\u00a0Star Trek : La Nouvelle G\u00e9n\u00e9ration\u00a0\u00bb intitul\u00e9 \u00ab\u00a0La Parfaite Compagne\u00a0\u00bb d\u00e9peint l&rsquo;\u00e9veil sexuel d&rsquo;une jeune femme et les d\u00e9fis auxquels elle et son environnement sont confront\u00e9s au cours de cette transition.<\/p>\n<p>Lorsque ce passage de l&rsquo;enfance \u00e0 l&rsquo;\u00e2ge adulte tourne mal, les gens peuvent se retrouver perp\u00e9tuellement bless\u00e9s et re-bless\u00e9s dans leurs relations ult\u00e9rieures les plus importantes, incapables de prendre soin de leurs propres limites, sexuelles ou autres. Ils vivent avec un d\u00e9sir constant d&rsquo;amour, de connexion et d&rsquo;approbation qui ne pourra jamais \u00eatre pleinement satisfait.<\/p>\n<p>Dans une certaine mesure, nous avons tous souffert des difficult\u00e9s de cette transition et il nous reste, \u00e0 tous, au moins, quelques vestiges d\u2019une telle blessure.<\/p>\n<h1 style=\"text-align: center;\"><strong>La PROMESSE de la ZONE INTERDITE<a id=\"promesse\"><\/a><\/strong><\/h1>\n<p>Lorsque ces personnes recherchent la gu\u00e9rison, elles peuvent pour la premi\u00e8re fois trouver un nouvel espoir sous la forme d\u2019une relation professionnelle de confiance avec une personne qui d\u00e9tient le pouvoir sur leur avenir. Il peut s&rsquo;agir d&rsquo;un th\u00e9rapeute qui d\u00e9tient la cl\u00e9 de leur sant\u00e9 psychologique et \u00e9motionnelle, d&rsquo;un enseignant ou d&rsquo;un mentor qui a le pouvoir de favoriser leur d\u00e9veloppement intellectuel ou professionnel, d&rsquo;un avocat, d&rsquo;un m\u00e9decin, d&rsquo;un gourou spirituel ou d&rsquo;un leader politique.<\/p>\n<p>Dans ce contexte, le psychiatre et analyste jungien Peter Rutter parle de <em>la zone interdite<\/em>.<\/p>\n<blockquote>\n<p>\u00ab\u00a0D&rsquo;une mani\u00e8re implicite, la zone interdite offre aux femmes qui y p\u00e9n\u00e8trent une qualit\u00e9 parentale de confiance.\u00a0\u00bb (Rutter 1989, p. 74)<\/p>\n<\/blockquote>\n<p><strong>Les relations en zone interdite sont calqu\u00e9es sur la dynamique parent-enfant en raison du d\u00e9s\u00e9quilibre des pouvoirs et de la confiance qui est transf\u00e9r\u00e9e au professionnel, cens\u00e9 toujours agir dans le meilleur int\u00e9r\u00eat de la personne dont il a la garde.<\/strong><\/p>\n<p>La relation th\u00e9rapeutique est con\u00e7ue en partie pour r\u00e9veiller les aspects infantiles&nbsp;des patients, afin que leurs blessures puissent \u00eatre soign\u00e9es et transform\u00e9es. La position de confiance et d\u2019autorit\u00e9 s\u2019accompagne \u00e9galement de la responsabilit\u00e9 \u00e9thique du r\u00f4le parental et donc du tabou li\u00e9 au sexe.<\/p>\n<p>Le consentement n\u2019a plus de sens dans cette situation. Tout comme les enfants n\u2019ont pas la capacit\u00e9 \u00e9motionnelle de refuser une relation incestueuse, qu\u2019elle soit v\u00e9cue litt\u00e9ralement ou symboliquement, les adultes, dans une relation en zone interdite, ne peuvent pas non plus donner leur consentement.<\/p>\n<blockquote>\n<p>\u00ab\u00a0D&rsquo;un point de vue psychologique, les violations de ces fronti\u00e8res \u00e9quivalent non seulement \u00e0 des viols mais aussi \u00e0 des actes d&rsquo;inceste.\u00a0\u00bb (Rutter 1989, p. 114)<\/p>\n<\/blockquote>\n<p>Tout au long de son livre&nbsp;de r\u00e9f\u00e9rence sur l&rsquo;exploitation sexuelle dans les relations professionnelles, Rutter montre \u00e0 quel point une relation sexuelle dans la zone interdite est incroyablement nocive, tant pour la personne au pouvoir que pour la personne dont elle a la garde.<\/p>\n<p>Bien que le comportement sexuel dans une relation professionnelle de confiance soit le pire type de franchissement des limites, tout comportement dans lequel une personne au pouvoir utilise une partie de la personne qui lui a \u00e9t\u00e9 confi\u00e9e \u00e0 son propre b\u00e9n\u00e9fice est nuisible.<\/p>\n<h2><strong>Transfert et contre-transfert \u00e9rotiques<\/strong><\/h2>\n<p>Rutter explore \u00e9galement les m\u00e9canismes psychologiques responsables de l&rsquo;attrait du sexe dans la zone interdite pour les participants et les t\u00e9moins. Ces m\u00e9canismes \u00e9clairent la difficult\u00e9 intrins\u00e8que \u00e0 sensibiliser \u00e0 ce ph\u00e9nom\u00e8ne r\u00e9pandu et \u00e0 s&rsquo;en pr\u00e9munir.<\/p>\n<p><strong>L&rsquo;intimit\u00e9 sexuelle vit dans notre psychisme collectif comme le symbole ultime de l&rsquo;exp\u00e9rience de l&rsquo;amour, de la passion et d&rsquo;un lien profond avec une autre personne, avec notre propre corps et notre psych\u00e9, avec la vie elle-m\u00eame ou avec le Divin.<\/strong><\/p>\n<p>Il est logique que dans le contexte d\u2019un nouvel espoir de gu\u00e9rison et de lien, qui \u00e9merge dans une relation en zone interdite, l\u2019un ou les deux participants puissent \u00eatre inond\u00e9s par un d\u00e9sir d\u2019intimit\u00e9. Et pourtant, pour une personne bless\u00e9e sexuellement, ce d\u00e9sir peut \u00eatre \u00e0 la fois terrifiant et farouchement combattu. Lorsque ces aspirations \u00e0 la proximit\u00e9 \u00e9motionnelle surgissent, c\u2019est la personne en position de pouvoir qui a la responsabilit\u00e9 de maintenir la tension et de surveiller les limites.<\/p>\n<p>Lorsque le transfert et\/ou le contre-transfert \u00e9rotique se constellent, les th\u00e9rapeutes doivent entreprendre la t\u00e2che d\u00e9licate de d\u00e9m\u00ealer les d\u00e9sirs d\u00e9routants pour eux-m\u00eames, <strong>tout en respectant les sentiments qui surgissent au cours du processus et en leur permettant d&rsquo;\u00eatre librement v\u00e9cus par le patient \u00e0 un niveau symbolique plut\u00f4t que litt\u00e9ral.<\/strong><\/p>\n<p>Nous ne devrions jamais faire honte \u00e0 nos patients pour leurs d\u00e9sirs profonds, m\u00eame si ceux-ci nous mettent mal \u00e0 l&rsquo;aise. Trop de rejet sous la forme d\u2019une d\u00e9fense trop forte contre la projection \u00e9rotique d\u2019un patient exclut l\u2019important potentiel de croissance et de gu\u00e9rison qu\u2019apporte cette constellation.<\/p>\n<blockquote>\n<p>\u00ab\u00a0Les images de contact sexuel avec des partenaires interdits repr\u00e9sentent souvent le d\u00e9sir que nous avons d&rsquo;\u00e9tablir le contact avec la partie de nous-m\u00eame que reproduit l&rsquo;image du partenaire interdit.\u00a0\u00bb (Rutter 1989, p.76)<\/p>\n<\/blockquote>\n<h2><strong>Hommes, femmes et personnes non-binaires<\/strong><\/h2>\n<p>Bien que l\u2019histoire que j\u2019interpr\u00e8te parle d\u2019une femme qui d\u00e9sire \u00eatre aim\u00e9e par un homme, je pense fortement que le processus de maturation d\u2019une femme a beaucoup en commun avec celui d\u2019un homme. Bien qu\u2019il existe des diff\u00e9rences, je m\u2019engage \u00e0 \u00e9crire du point de vue de notre exp\u00e9rience humaine commune en tant que personne, quelle que soit notre identit\u00e9 de genre ou notre orientation sexuelle.<\/p>\n<p>Avec cette d\u00e9cision, j\u2019esp\u00e8re parvenir \u00e0 une description plus large dans laquelle tout le monde peut se reconna\u00eetre et qui promeut l\u2019\u00e9galit\u00e9 des opportunit\u00e9s et les droits \u00e0 la protection et \u00e0 l\u2019empathie.<\/p>\n<h1 style=\"text-align: center;\"><strong>La PARFAITE <\/strong><strong>COMPAGNE <\/strong><strong>de STAR TREK<\/strong><a id=\"mate\"><\/a><\/h1>\n<p>Dans \u00ab\u00a0La Parfaite Compagne\u00a0\u00bb (Star Trek : La Nouvelle G\u00e9n\u00e9ration, S5E21), le capitaine Picard accepte d&rsquo;organiser \u00e0 bord du vaisseau Enterprise une c\u00e9r\u00e9monie de r\u00e9conciliation pour deux races extraterrestres. Les Kriosiens et les Valtais sont en guerre depuis des si\u00e8cles \u00e0 cause d&rsquo;un conflit n\u00e9 de deux fr\u00e8res qui se sont battus pour l&rsquo;amour d&rsquo;une femme extraordinaire.<\/p>\n<p>Elle \u00e9tait une <em>m\u00e9tamorphe empathique<\/em>, \u00ab\u00a0dot\u00e9e du pouvoir de deviner le d\u00e9sir de tout partenaire potentiel, capable de savoir \u00e0 l&rsquo;avance tout ce qu&rsquo;il attend d&rsquo;une femme et de devenir pour lui cette femme\u00a0\u00bb.<\/p>\n<p>Une telle femme ne na\u00eet qu\u2019une fois sur sept g\u00e9n\u00e9rations. Pour parvenir \u00e0 la paix entre leurs deux civilisations en guerre, les Kriosiens ont amen\u00e9 Kamala, \u00e9galement une m\u00e9tamorphe empathique, \u00e0 offrir au chancelier Valtais Alrik comme compagnon. Cette offrande de paix a \u00e9t\u00e9 n\u00e9goci\u00e9e d\u00e8s sa naissance.<\/p>\n<h2><strong>\u00c9veil sexuel<\/strong><\/h2>\n<p>Kamala est embarqu\u00e9e sous le couvert du secret. Elle a \u00e9t\u00e9 mise en stase et est conserv\u00e9e dans la soute dans ce qui ressemble \u00e0 un \u0153uf lumineux \u00e0 taille humaine. Personne n&rsquo;aurait \u00e9t\u00e9 au courant sans les deux <em>Ferengis<\/em> qui sont venus \u00e0 bord avec une ruse et l&rsquo;intention de voler la pr\u00e9cieuse femme anima pour un gain financier.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24751\" src=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-stasis.png\" alt=\"\" width=\"600\" height=\"451\" srcset=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-stasis.png 600w, https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-stasis-300x226.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Les Ferengis sont une esp\u00e8ce humano\u00efde t\u00e9n\u00e9breuse, connue pour leur amour du profit \u00e9conomique. Ils ont fond\u00e9 toute une civilisation sur le culte de l\u2019argent. Ils sont connus pour leur qu\u00eate odieuse, impitoyable, mais souvent innocemment stupide, du plaisir infantile, du pouvoir et de la richesse.<\/p>\n<p>\u00c0 la mani\u00e8re du Trickster, un probl\u00e8me technique se produit alors qu&rsquo;ils tentent de voler l&rsquo;\u0153uf, provoquant le r\u00e9veil pr\u00e9matur\u00e9 de Kamala de la stase. On comprend vite pourquoi les Kriosiens ont tent\u00e9 de la cacher. Premi\u00e8rement, le capitaine Picard se montre peu compr\u00e9hensif face \u00e0 l&rsquo;utilisation de son vaisseau pour transporter un \u00eatre conscient consid\u00e9r\u00e9 comme une propri\u00e9t\u00e9.<\/p>\n<p>Deuxi\u00e8mement, Kamala, en tant que m\u00e9tamorphe empathique, est dans la derni\u00e8re \u00e9tape de son processus de maturation sexuelle et affirme que cela peut \u00eatre assez inconfortable pour les hommes qui l&rsquo;entourent. Une m\u00e9tamorphe empathique change de personnalit\u00e9 selon l&rsquo;homme avec qui elle est, \u00ab\u00a0jusqu&rsquo;\u00e0 ce qu&rsquo;elle atteigne le stade de l&rsquo;osmose, et l\u00e0 son adaptation \u00e0 l&rsquo;homme du moment sera la derni\u00e8re, et elle deviendra sa partenaire id\u00e9ale d\u00e9finitive\u00a0\u00bb.<\/p>\n<p>Alors que le commandant Riker l&rsquo;accompagne jusqu&rsquo;\u00e0 ses quartiers, o\u00f9 l&rsquo;ambassadeur Kriosien lui dit de rester, on se fait une id\u00e9e du risque, car sa pr\u00e9sence devient vite hautement provocatrice et s\u00e9duisante. Bien que le commandant Riker parvienne \u00e0 s&rsquo;\u00e9loigner apr\u00e8s seulement un baiser passionn\u00e9, un homme avec moins de ma\u00eetrise de l&rsquo;ego ou une position \u00e9thique plus faible aurait succomb\u00e9 instantan\u00e9ment \u00e0 son charme.<\/p>\n<h2><strong>Le mythe masculin du f\u00e9minin<\/strong><\/h2>\n<p>Comme cela arrive souvent dans les \u00e9pisodes de Star Trek, une partie de la psychologie et du comportement humain est amplifi\u00e9e et explor\u00e9e. Il s\u2019agit ici de l\u2019\u00e9veil sexuel d\u2019une adolescente en pleine pubert\u00e9 et du fantasme masculin entourant les femmes sexuellement m\u00fbres. Rutter identifie trois parties du mythe culturel qui expliquent les attitudes int\u00e9rieures qui fa\u00e7onnent la mani\u00e8re&nbsp;dont les femmes sont per\u00e7ues par les hommes et la fa\u00e7on dont les femmes se voient elles-m\u00eames.<\/p>\n<p><strong>D\u00e9f\u00e9rence<\/strong><\/p>\n<blockquote>\n<p>\u00ab\u00a0Dans la mythologie masculine, une femme doit avant tout montrer de la d\u00e9f\u00e9rence pour un homme. Pour l&rsquo;homme, la femme id\u00e9ale doit \u00eatre disponible comme partenaire sexuelle et source de confort \u00e9motionnel; elle doit \u00eatre la compagne qui s&rsquo;occupe de la maison et \u00e9l\u00e8ve les enfants.\u00a0\u00bb (Rutter 1989, p. 88)<\/p>\n<\/blockquote>\n<p>Malgr\u00e9 notre malaise face \u00e0 une telle in\u00e9galit\u00e9 et au mot \u00ab\u00a0d\u00e9f\u00e9rence\u00a0\u00bb, nous ne pouvons ignorer que cette id\u00e9e reste enracin\u00e9e chez les hommes comme chez les femmes. Il faut de la conscience et des efforts pour ne pas simplement suivre le mod\u00e8le patriarcal.<\/p>\n<p>Les femmes d\u2019un groupe s\u2019en remettent encore largement \u00e0 l\u2019opinion d\u2019un homme. Des \u00e9tudes montrent que les publications d\u2019auteurs masculins <em>sont associ\u00e9es <\/em>\u00e0 une meilleure qualit\u00e9 scientifique et sont susceptibles de <em>susciter<\/em> davantage d\u2019int\u00e9r\u00eat pour la collaboration que celles \u00e9crites par des femmes (Knobloch-Westerwick et al. 2013).<\/p>\n<p>En r\u00e9action \u00e0 cette situation injuste, certaines femmes adoptent l&rsquo;attitude oppos\u00e9e, consid\u00e9rant que les hommes ont le devoir de se soumettre \u00e0 tous leurs d\u00e9sirs.&nbsp;De m\u00eame, certains hommes ont int\u00e9rioris\u00e9 cette notion et croient que la seule fa\u00e7on de retenir leur partenaire f\u00e9minine est de toujours dire \u00ab\u00a0oui, ch\u00e9rie\u00a0\u00bb.<\/p>\n<p>Je propose de formuler le mythe de d\u00e9f\u00e9rence, quelque soit le genre, sous la forme suivante : soit nous devons nous en remettre \u00e0 l\u2019autre, soit nous devons nous assurer que l&rsquo;autre se fie \u00e0 nous. Ou encore : soit nous dominons, soit nous sommes domin\u00e9s.<\/p>\n<p><strong>Pouvoirs de gu\u00e9rison f\u00e9minins<\/strong><\/p>\n<blockquote>\n<p>\u00ab\u00a0La seconde composante du mythe masculin du f\u00e9minin concerne les grands pouvoirs de gu\u00e9rison, de chaleur et de sexualit\u00e9 que les hommes attribuent aux femmes. Les hommes ont la ferme conviction que les femmes d\u00e9tiennent ces pouvoirs afin qu\u2019ils puissent en \u00eatre les seuls b\u00e9n\u00e9ficiaires.\u00a0\u00bb (Rutter 1989, p. 89)<\/p>\n<\/blockquote>\n<p>Il va de soi qu&rsquo;il existe un mythe f\u00e9minin qui, bien que semblant l\u00e9g\u00e8rement diff\u00e9rent \u00e0 premi\u00e8re vue, partage des similitudes avec celui du masculin.<\/p>\n<p>Lors d\u2019un exercice d\u2019improvisation avec un groupe d\u2019\u00e9tudiantes en ing\u00e9nierie tr\u00e8s d\u00e9termin\u00e9es dans leurs convictions, je me suis r\u00e9cemment rappel\u00e9e \u00e0 quel point l&rsquo;attrait des maris riches est omnipr\u00e9sent. M\u00eame si ces femmes n\u2019auront aucune difficult\u00e9 \u00e0 subvenir \u00e0 leurs besoins dans un style de vie confortable, plusieurs d\u2019entre elles ont n\u00e9anmoins r\u00e9v\u00e9l\u00e9 un d\u00e9sir profond d&rsquo;\u00eatre aim\u00e9es et prises en charge par un homme riche capable de leur offrir une maison belle et luxueuse.<\/p>\n<p>Mais si le confort est ce qu\u2019elles d\u00e9sirent, pourquoi ne s\u2019efforcent-elles pas de devenir riches elles-m\u00eames ? Peut-\u00eatre parce qu\u2019au fond, les femmes croient encore que les hommes d\u00e9tiennent le pouvoir financier (et professionnel) qui peut ensuite leur \u00eatre conf\u00e9r\u00e9.<\/p>\n<p>Les mythes masculins et f\u00e9minins semblent devenir de plus en plus interchangeables. De nombreux hommes sont parfaitement ouverts aux avantages d&rsquo;avoir une \u00e9pouse riche et prosp\u00e8re, et les femmes attendent \u00e9galement de leur mari ou partenaire soins nourrissants et gu\u00e9rison sexuelle.<\/p>\n<p><strong>Hommes, femmes et personnes non-binaires sont tous incit\u00e9s \u00e0 rechercher une intimit\u00e9 sexuelle avec un partenaire potentiel sur lequel ils ont projet\u00e9 leurs propres qualit\u00e9s et pouvoirs non encore int\u00e9gr\u00e9s. Ils croient inconsciemment que l\u2019intimit\u00e9 est le seul moyen de les obtenir.<\/strong><\/p>\n<p>Les aspects mentionn\u00e9s du mythe masculin du f\u00e9minin de Rutter sont amplifi\u00e9s dans l\u2019id\u00e9e de la m\u00e9tamorphe empathique. De plus, il n\u2019est m\u00eame pas n\u00e9cessaire de se sentir coupable de<em> se servir de<\/em> la femme de cette mani\u00e8re. Ce n\u2019est pas de l\u2019exploitation, car c\u2019est sa vraie nature, et s\u2019en remettre aux souhaits des hommes est sa plus grande source de bonheur.<\/p>\n<p>Cette attitude s&rsquo;approche dangereusement de celle qui persiste encore aujourd\u2019hui dans les d\u00e9bats sur le viol et les abus sexuels. Bien que les lois soient devenues plus efficaces pour combattre les soi-disant propos tels que \u00ab\u00a0elle l&rsquo;a voulu\u00a0\u00bb et \u00ab\u00a0elle l&rsquo;a demand\u00e9\u00a0\u00bb, et qu\u2019il soit d\u00e9sormais socialement inacceptable de le dire \u00e0 voix haute, il faudra beaucoup de temps pour que les changements conscients soient int\u00e9gr\u00e9s dans notre inconscient.<\/p>\n<p>Mais il y a de l\u2019espoir pour une transformation. Les m\u00eames \u00e9tudiantes en ing\u00e9nierie qui s&rsquo;imaginent avec un mari riche fr\u00e9quentent l\u2019universit\u00e9 en hauts courts et sans soutien-gorge, d\u00e9clarant qu\u2019il n\u2019est pas de leur responsabilit\u00e9 de prendre soin du d\u00e9sir des hommes et qu\u2019il est temps que les hommes assument la responsabilit\u00e9 de leurs propres sentiments et d\u00e9sirs. Elles ont tout \u00e0 fait raison, peu importe \u00e0 quel point cela peut rendre mal \u00e0 l\u2019aise les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes ou susciter notre inqui\u00e9tude pour elles.<\/p>\n<p>Les individus ne devraient pas \u00eatre tenus responsables de ce que les autres projettent sur eux. Reste \u00e0 esp\u00e9rer que plus le nombre de personnes qui s&rsquo;\u00e9l\u00e8vent et se rebellent contre ces projections culturelles s&rsquo;accro\u00eet, plus la transformation collective s&rsquo;effectuera rapidement.<\/p>\n<h2><strong>La compassion exploit\u00e9e<\/strong><\/h2>\n<p>Au d\u00e9part, le capitaine Picard accepte la situation de Kamala parce qu\u2019il a jur\u00e9 de ne pas s\u2019immiscer dans les civilisations extraterrestres et parce qu\u2019elle semble savoir ce qu\u2019elle fait.<\/p>\n<p>Cependant, le Dr Beverly Crusher, qui incarne tout au long de la s\u00e9rie la voix de la conscience et de la protection des droits de tous les \u00eatres conscients (voir <a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/ombre-en-star-trek\/\">Les Borgs de Star Trek : symbole de l\u2019inconscient collectif dans son aspect d\u2019ombre d\u00e9vorante et annihilante<\/a>), pense autrement. Elle utilise des termes comme <em>prostitution<\/em> et <em>esclavage<\/em> et souligne que Kamala a \u00e9t\u00e9 \u00ab\u00a0conditionn\u00e9e depuis son plus jeune \u00e2ge pour trouver normal de n&rsquo;exister qu&rsquo;en fonction du plaisir des hommes.<\/p>\n<p>Certaines personnes ont en effet \u00e9t\u00e9 conditionn\u00e9es par leur \u00e9ducation \u00e0 croire qu\u2019elles n\u2019existent que pour r\u00e9pondre aux besoins d\u2019autrui. Parfois, les parents&nbsp;ont des blessures d&rsquo;une telle gravit\u00e9 que la seule mani\u00e8re pour un enfant d\u2019esp\u00e9rer recevoir une attention positive (et survivre) est de r\u00e9pondre \u00e0 leurs besoins. De cette mani\u00e8re, l\u2019enfant int\u00e8gre inconsciemment le message selon lequel ses propres besoins, espoirs et d\u00e9sirs ne sont pas importants.<\/p>\n<p>En tant qu\u2019adultes, ces personnes risquent de reproduire la m\u00eame dynamique dans chaque relation importante ult\u00e9rieure. Rutter identifie ce sch\u00e9ma de <strong>compassion exploit\u00e9e<\/strong> comme l\u2019une des quatre cat\u00e9gories de blessures qui exposent les individus \u00e0 des violations ult\u00e9rieures des limites sexuelles. Ces personnes sont tr\u00e8s sensibles aux blessures de la personne en qui elles ont plac\u00e9 leur confiance et leur espoir de gu\u00e9rison. Elles auront du mal \u00e0 refuser toute demande visant \u00e0 panser les blessures de l\u2019autre, qu\u2019elle soit manifeste ou projet\u00e9e de mani\u00e8re inconsciente.<\/p>\n<h2><strong>Doubles standards<\/strong><\/h2>\n<p>Les conceptions contemporaines de l&rsquo;\u00e9galit\u00e9 des sexes exigent que nous appliquions les id\u00e9es importantes de Rutter \u00e0 l&rsquo;exp\u00e9rience de tous les \u00eatres humains. C\u2019est particuli\u00e8rement crucial aujourd&rsquo;hui.<\/p>\n<p>Bien qu&rsquo;il semble y avoir une meilleure compr\u00e9hension dans la population g\u00e9n\u00e9rale du pr\u00e9judice caus\u00e9 par une relation amoureuse et\/ou sexuelle entre un th\u00e9rapeute masculin et une patiente, <strong>nous voyons encore des th\u00e9rapeutes f\u00e9minines nouer des relations avec leurs patients masculins dans des s\u00e9ries t\u00e9l\u00e9vis\u00e9es, sans aucune reconnaissance du pr\u00e9judice caus\u00e9 au patient.<\/strong><\/p>\n<p>Dans la s\u00e9rie \u00ab\u00a0Perception\u00a0\u00bb (2012-2015), la psychiatre Caroline entame une relation amoureuse avec son patient schizophr\u00e8ne Daniel. Lorsque la relation prend fin, elle admet qu\u2019elle aurait d\u00fb se garder de penser que cela serait bon <em>pour elle<\/em>. L&rsquo;impact n\u00e9faste sur Daniel n&rsquo;est jamais reconnu par elle ni mentionn\u00e9 d&rsquo;une autre mani\u00e8re dans la s\u00e9rie.<\/p>\n<p>Au d\u00e9but de la saison 7 de \u00ab\u00a0Suits, avocats sur mesure\u00a0\u00bb (2017-2018), le personnage principal, Harvey, demande \u00e0 son ancienne th\u00e9rapeute Paula de sortir avec lui, affirmant que suffisamment de temps s&rsquo;est \u00e9coul\u00e9 depuis la fin de leur th\u00e9rapie. Ils sortent d\u00eener, mais quand il devient \u00e9vident qu&rsquo;Harvey nie \u00eatre en crise et avoir besoin d&rsquo;une th\u00e9rapie, elle s&rsquo;\u00e9nerve et dit :<\/p>\n<blockquote>\n<p>\u00ab\u00a0Vous n&rsquo;avez jamais pens\u00e9 que je puisse r\u00eaver de vous ? R\u00eaver qu&rsquo;un soir vous arriveriez \u00e0 mon cabinet alors je m&rsquo;appr\u00eatais \u00e0 rentrer. Je me retournerais, vous seriez l\u00e0. Vous ne prononceriez pas un mot, mais&#8230; vous me prendriez dans vos bras, et vous m&#8217;embrasseriez. Et ce serait le d\u00e9but d&rsquo;une belle histoire. Oui, c&rsquo;\u00e9tait mon r\u00eave.\u00a0\u00bb (Suits, avocats sans mesures, S7E1 : L&rsquo;heure du choix)<\/p>\n<\/blockquote>\n<p>Elle continue en lui disant qu&rsquo;ils ne peuvent pas sortir ensemble et qu&rsquo;elle ne peut plus \u00eatre sa th\u00e9rapeute. Mais le lendemain, Harvey se rend chez elle en voiture, la prend dans ses bras et l&#8217;embrasse. Il r\u00e9alise son fantasme et ils entament une relation. Harvey a perdu son th\u00e9rapeute alors qu&rsquo;il en avait besoin.<\/p>\n<p>Le caract\u00e8re prohib\u00e9 de la relation et la crainte d&rsquo;\u00eatre jug\u00e9 par ses pairs sont reconnus, mais le pr\u00e9judice caus\u00e9 \u00e0 son ancien patient n&rsquo;est jamais abord\u00e9.<\/p>\n<p><strong>\u00c0 ce jour, persiste \u00e9galement une double norme dans la mani\u00e8re dont nous, culturellement, percevons un enseignant ou professeur qui s&rsquo;engage dans une relation amoureuse avec un \u00e9l\u00e8ve ou \u00e9tudiant.<\/strong><\/p>\n<p>L&rsquo;enseignant ou professeur est d\u00e9sormais largement consid\u00e9r\u00e9 comme un pr\u00e9dateur abusant de son pouvoir et de son autorit\u00e9, surtout si l&rsquo;\u00e9l\u00e8ve ou l&rsquo;\u00e9tudiante est beaucoup plus jeune que lui.<\/p>\n<p>En revanche, lorsque c&rsquo;est une enseignante ou professeure qui a une relation avec son \u00e9l\u00e8ve ou \u00e9tudiant, cela est souvent per\u00e7u comme romantique et excitant. L&rsquo;\u00e9tudiante est alors vue comme une victime, tandis que l&rsquo;\u00e9tudiant masculin est consid\u00e9r\u00e9 comme chanceux d&rsquo;avoir une femme exp\u00e9riment\u00e9e pour l&rsquo;initier \u00e0 l&rsquo;art du sexe.<\/p>\n<p><strong>Il est temps que le comportement abusif des femmes en position de pouvoir, bien que moins fr\u00e9quent, soit \u00e9galement reconnu et d\u00e9nonc\u00e9.<\/strong><\/p>\n<p>Nos soci\u00e9t\u00e9s ont encore beaucoup de progr\u00e8s \u00e0 faire pour prot\u00e9ger les jeunes femmes et soutenir les femmes victimes d&rsquo;exploitation sexuelle. Cependant, la situation est encore plus pr\u00e9caire pour les hommes.<\/p>\n<p>Souvent, les hommes ne sont m\u00eame pas consid\u00e9r\u00e9s comme des victimes, m\u00eame si la situation est exactement parall\u00e8le. Les hommes devraient avoir acc\u00e8s \u00e0 la m\u00eame protection, empathie et prise en charge que les femmes. Il n\u2019est pas moins nocif pour un homme d\u2019\u00eatre exploit\u00e9 sexuellement que pour une femme. Le mythe \u00e0 l\u2019origine de ce double standard consiste en deux parties.<\/p>\n<ul>\n<li>La premi\u00e8re partie du mythe postule que les hommes sont plus forts que les femmes, qu&rsquo;ils sont responsables de toute relation physique entre eux, et donc peu susceptibles d&rsquo;\u00eatre victimes d&rsquo;exploitation sexuelle.&nbsp;<\/li>\n<li>La deuxi\u00e8me partie du mythe est que les hommes sont tellement programm\u00e9s pour le sexe qu\u2019il est impossible de leur faire du mal lorsqu\u2019il leur est <em>propos\u00e9<\/em>, m\u00eame par une personne qui a du pouvoir sur eux.<\/li>\n<\/ul>\n<p>Ces croyances sont perp\u00e9tu\u00e9es \u00e0 la fois par les femmes et les hommes, ainsi que par les st\u00e9r\u00e9otypes que nous continuons de voir dans les films, la publicit\u00e9, les livres et la musique. Les deux croyances sont fausses.<\/p>\n<p>Notez \u00e9galement la diff\u00e9rence dans notre langage quotidien : on <em>demande<\/em> du sexe aux femmes, mais on <em>propose<\/em> ou <em>offre<\/em> du sexe aux hommes. Cela rejoint clairement la deuxi\u00e8me partie du mythe masculin de Rutter, selon laquelle les femmes sont d\u00e9tentrices du pouvoir sexuel, qui peut ensuite \u00eatre accord\u00e9 aux hommes sur demande.<\/p>\n<h1 style=\"text-align: center;\"><strong>AMOUR de TRANSFERT<\/strong><a id=\"transference\"><\/a><\/h1>\n<p>Lorsque le capitaine Picard d\u00e9couvre que Kamala est confin\u00e9e dans ses quartiers, il d\u00e9cide d&rsquo;aller v\u00e9rifier que tout se passe bien. Lorsqu\u2019elle commence \u00e0 s\u2019adapter de mani\u00e8re s\u00e9duisante \u00e0 ses d\u00e9sirs les plus profonds, il comprend imm\u00e9diatement : \u00ab\u00a0Non. Arr\u00eatez. Arr\u00eatez s&rsquo;il vous pla\u00eet\u2026 ce que vous faites avec les hommes.\u00a0\u00bb Mais elle r\u00e9pond que c&rsquo;est simplement sa nature. \u00ab\u00a0Elle ne peut changer, ni ne le veut d&rsquo;ailleurs avant que vienne le moment o\u00f9 elle appartiendra \u00e0 son partenaire d\u00e9finitif.\u00a0\u00bb<\/p>\n<p>De m\u00eame, un patient dont le processus de maturation a \u00e9t\u00e9 perturb\u00e9 d\u2019une mani\u00e8re ou d\u2019une autre ne pourra pas simplement cesser de se rapporter aux autres de la mani\u00e8re dont il a \u00e9t\u00e9 conditionn\u00e9. Cela est encore plus vrai pour les relations qui portent la promesse d\u2019espoir et de gu\u00e9rison.<\/p>\n<p>La r\u00e9solution qui accompagne l&rsquo;attachement \u00e0 son partenaire d\u00e9finitif peut \u00eatre interpr\u00e9t\u00e9e comme la transformation qui se produit lorsque ces patients \u00e9tablissent une relation avec la figure int\u00e9rieure de leur \u00e2me : leur Anima\/Animus ou leur Bien-Aim\u00e9.<\/p>\n<p>Le capitaine Picard l&rsquo;interroge sur ses propres souhaits et besoins, et elle r\u00e9pond qu&rsquo;ils sont combl\u00e9s par ce qu&rsquo;elle offre aux autres. Donner lui procure du plaisir. Lorsqu\u2019elle est seule, elle se sent incompl\u00e8te.<\/p>\n<p>En tant que capitaine, son objectif est de s&rsquo;assurer que Kamala, qui est \u00e0 bord de son vaisseau et donc sous sa garde, soit bien trait\u00e9e et libre de faire ses propres choix. Lorsqu&rsquo;elle utilise son charme sur lui, sa premi\u00e8re r\u00e9action est de lui demander d&rsquo;arr\u00eater. Mais elle ne peut pas s\u2019arr\u00eater car c\u2019est sa nature. Alors, il la raisonne et essaie de la faire r\u00e9fl\u00e9chir \u00e0 ses propres souhaits. Mais elle ne peut pas le faire, du moins pas encore, et elle retombe dans son comportement complaisant.<\/p>\n<p>Il s\u2019agit d\u2019une dynamique que les th\u00e9rapeutes pourraient reconna\u00eetre dans leur cabinet, m\u00eame si elle ne se joue pas de mani\u00e8re aussi \u00e9vidente. Les personnes que nous rencontrons en th\u00e9rapie sont celles qui ont \u00e9t\u00e9 bless\u00e9es. Elles se remettent entre nos mains avec l\u2019espoir et la confiance que nous leur permettrons la gu\u00e9rison \u00e0 laquelle elles aspirent tant. Et elles nous montrent leur maladie, leur mod\u00e8le&nbsp;autodestructeur comme elles le peuvent : en le revivant dans le transfert (Rutter 1989, p. 20).<\/p>\n<p>Un comportement excessivement complaisant ou agr\u00e9able de la part d&rsquo;un patient, qu&rsquo;il soit manifeste ou inconscient, qu&rsquo;il soit sexuel ou non, r\u00e9v\u00e8le un profond d\u00e9sir d&rsquo;amour et d&rsquo;affection, ainsi qu&rsquo;une d\u00e9finition probl\u00e9matique de leurs limites et un potentiel historique de violations de ces limites. Le fait est que nos patients n&rsquo;y peuvent rien. En nous exposant leur mod\u00e8le, ils font exactement ce qu&rsquo;ils sont cens\u00e9s faire : ils nous pr\u00e9sentent le probl\u00e8me afin que nous puissions y travailler ensemble.<\/p>\n<h2><strong>Transfert personnel et arch\u00e9typal<\/strong><\/h2>\n<p>Malgr\u00e9 les avertissements de l&rsquo;ambassadeur Kriosien, le capitaine Picard n\u00e9gocie une certaine libert\u00e9 de mouvement pour Kamala. Le lieutenant Data, un andro\u00efde et donc immunis\u00e9 contre son attrait sexuel, est d\u00e9sign\u00e9 pour la chaperonner et la prot\u00e9ger pendant qu&rsquo;elle explore le vaisseau. Cependant, elle esp\u00e9rait passer plus de temps avec le capitaine Picard.<\/p>\n<p>La r\u00e9action automatique et inconsciente de Kamala \u00e0 devenir ce que le capitaine Picard d\u00e9sire chez son \u00e2me s\u0153ur peut \u00eatre consid\u00e9r\u00e9e comme analogue aux <strong>projections personnelles et historiques qu&rsquo;un patient apporte \u00e0 la relation transfert\/contre-transfert en th\u00e9rapie<\/strong>.<\/p>\n<p>Au cours du travail th\u00e9rapeutique, nous esp\u00e9rons dissoudre ce type de projections afin que nos patients puissent \u00eatre lib\u00e9r\u00e9s de leur tendance \u00e0 r\u00e9p\u00e9ter les blessures de leur pass\u00e9 avec nous et avec les autres, et qu&rsquo;ils puissent ainsi avoir un plus large \u00e9ventail de choix dans leurs relations interpersonnelles et leur rapport \u00e0 eux-m\u00eames. Ceci est normalement r\u00e9alis\u00e9 dans le cadre du travail de transfert\/contre-transfert et par l&rsquo;utilisation th\u00e9rapeutique de la reconstruction.<\/p>\n<blockquote>\n<p>\u00ab\u00a0La reconstruction, il convient de le noter, est essentiellement diff\u00e9rente de l&rsquo;anamn\u00e8se ou du simple souvenir du pass\u00e9. Elle se produit au coup par coup au cours d&rsquo;une longue analyse et se construit petit \u00e0 petit \u00e0 partir de souvenirs et d&rsquo;interpr\u00e9tations \u00e9mergents. L\u2019histoire se constelle au cours d\u2019une analyse, et cette constellation d\u00e9pend de l\u2019\u00e9nergie du processus de transfert\/contre-transfert.\u00a0\u00bb (Stein 1987, p. 52)<\/p>\n<\/blockquote>\n<p>Cependant, il existe une partie de Kamala qui ressent une attraction envers le capitaine Picard qui d\u00e9passe son adaptation automatique et conditionn\u00e9e aux hommes. Lorsqu&rsquo;elle sort de sa stase, elle se dirige instantan\u00e9ment vers lui, ressentant son autorit\u00e9. On peut \u00e9galement imaginer qu&rsquo;elle l&rsquo;a choisi pour incarner son Bien-Aim\u00e9 int\u00e9rieur d\u00e8s le premier instant.<\/p>\n<p>Quelque chose de profond en elle a saisi l&rsquo;opportunit\u00e9 de son r\u00e9veil pr\u00e9matur\u00e9 accidentel pour \u00e9chapper au monde de l&rsquo;inconscience conditionn\u00e9e et \u0153uvrer vers une plus grande conscience. Guid\u00e9e par le Soi, elle a reconnu les qualit\u00e9s incarn\u00e9es par le capitaine Picard comme une partie m\u00e9connue d&rsquo;elle-m\u00eame et a ressenti le d\u00e9sir et la curiosit\u00e9 de s&rsquo;en approcher.<\/p>\n<p>Dans le cadre analytique, cela fait partie du <strong>transfert arch\u00e9typal<\/strong>. Alors que nous visons \u00e0 dissoudre les projections personnelles et historiques, il en va diff\u00e9remment pour les projections impersonnelles ou arch\u00e9typales, qui regardent vers l\u2019avenir et non vers le pass\u00e9.<\/p>\n<blockquote>\n<p>\u00ab\u00a0Ces contenus arch\u00e9typaux du transfert ne peuvent et ne doivent pas \u00eatre dissous, et ils n\u2019exigent pas non plus d\u2019interpr\u00e9tation. Au lieu de cela, ils n\u00e9cessitent une sorte de reconnaissance dans l\u2019analyse.\u00a0\u00bb (Wiener 2009, p. 24)&nbsp;<\/p>\n<\/blockquote>\n<p>C\u2019est en partie pourquoi il est si important de ne pas rejeter nos patients dans leurs v\u00e9ritables sentiments d\u2019amour \u00e0 notre \u00e9gard, m\u00eame si ces sentiments s\u2019expriment par un d\u00e9sir d\u2019intimit\u00e9 sexuelle, que nous pouvons ou non trouver attrayant.<\/p>\n<p>M\u00eame si nous ne pouvons jamais c\u00e9der au d\u00e9sir de vivre ce d\u00e9sir dans le monde ext\u00e9rieur, nous devons trouver un moyen de reconna\u00eetre et d\u2019honorer leurs sentiments, et m\u00eame de les amplifier \u00e0 un niveau symbolique.<\/p>\n<h2><strong>L&rsquo;art d&rsquo;appr\u00e9cier nos patients<\/strong><\/h2>\n<p>En se promenant dans le vaisseau en compagnie du lieutenant Data, Kamala se mue instantan\u00e9ment en la parfaite compagne. Tel un cam\u00e9l\u00e9on, elle s&rsquo;adapte et \u00e9volue avec chaque homme qu&rsquo;elle croise. Certains membres de l&rsquo;\u00e9quipage prennent conscience du danger de succomber \u00e0 son charisme juste \u00e0 temps et s&rsquo;\u00e9loignent par devoir \u00e9thique envers leur vaisseau, leur capitaine et les n\u00e9gociations de paix auxquelles ils contribuent.<\/p>\n<p>L&rsquo;andro\u00efde Data intervient pour prot\u00e9ger Kamala de quelques individus moins scrupuleux qui sont pr\u00eats \u00e0 accepter simplement ce qu&rsquo;elle propose. Une altercation physique est sur le point d&rsquo;\u00e9clater.<\/p>\n<p>Cette sc\u00e8ne souligne que dans le monde ext\u00e9rieur, symbolis\u00e9 par le vaisseau spatial au-del\u00e0 des quartiers de Kamala, les dangers sont doubles. Soit les propositions inconscientes des patients sont accept\u00e9es, entra\u00eenant une r\u00e9p\u00e9tition du sentiment d&rsquo;\u00eatre utilis\u00e9 et potentiellement abus\u00e9, soit leurs propositions&nbsp;sont rejet\u00e9es et les gens fuient leur pr\u00e9sence per\u00e7ue comme dangereuse.<\/p>\n<p>M\u00eame si l&rsquo;on pourrait supposer que cette derni\u00e8re option est moins pr\u00e9judiciable, elle peut \u00eatre per\u00e7ue comme encore plus blessante, car elle repr\u00e9sente un rejet des dons particuliers de connexion et d&rsquo;amour que nos patients ont \u00e0 offrir.<\/p>\n<p><strong>Dans les deux cas, aucune relation saine n&rsquo;est envisageable, ce qui peut engendrer chez les patients un sentiment d&rsquo;ins\u00e9curit\u00e9 et les conduire \u00e0 faire encore plus de compromis sur leurs propres d\u00e9sirs pour plaire aux autres.<\/strong><\/p>\n<p>De retour dans ses quartiers, Kamala propose au capitaine Picard de rester l\u00e0-bas de son plein gr\u00e9, \u00e0 condition qu&rsquo;il accepte de venir lui rendre visite. S&rsquo;ensuit alors une sc\u00e8ne de s\u00e9duction complexe. Pas une s\u00e9duction physique, mais une s\u00e9duction intellectuelle et spirituelle, semblable \u00e0 celle qui pourrait avoir lieu dans un cadre th\u00e9rapeutique.<\/p>\n<p>Kamala continue \u00e0 tenter d&rsquo;\u00e9tablir un lien affectif avec lui sur des sujets qui le passionnent : l&rsquo;arch\u00e9ologie, Shakespeare et les magnifiques jardins de son enfance. Le capitaine Picard se permet d&rsquo;appr\u00e9cier sa compagnie et ses dons de connexion qui lui sont sp\u00e9cialement destin\u00e9s, tant que leur interaction reste platonique et innocente. Il poss\u00e8de suffisamment de force de l&rsquo;ego, de connaissance de soi et de sens des responsabilit\u00e9s pour demeurer en sa pr\u00e9sence de mani\u00e8re saine : sans l&rsquo;exploiter, mais sans la fuir ou la rejeter non plus.<\/p>\n<p><strong>Il est essentiel pour un th\u00e9rapeute de favoriser ce type de connexion authentique au sein du cadre analytique.<\/strong><\/p>\n<p>Beaucoup de personnes qui entament une th\u00e9rapie n&rsquo;ont jamais exp\u00e9riment\u00e9 le sentiment d&rsquo;\u00eatre v\u00e9ritablement valoris\u00e9es par leurs figures parentales, dans un environnement s\u00e9curis\u00e9 o\u00f9 elles n&rsquo;ont pas besoin de se sacrifier pour obtenir ne serait-ce qu&rsquo;un brin d&rsquo;affection.<\/p>\n<p>De v\u00e9ritables moments de gu\u00e9rison peuvent \u00e9merger lorsque, en tant que th\u00e9rapeutes, nous parvenons \u00e0 g\u00e9rer habilement la charge \u00e9motionnelle, tout en maintenant fermement les limites de la sph\u00e8re sexuelle. Il est essentiel de reconna\u00eetre et d&rsquo;appr\u00e9cier les moments de connexion authentique et les dons uniques de nos patients, en particulier lorsqu&rsquo;ils sont partag\u00e9s de mani\u00e8re saine. Comme le capitaine Picard, nous devons trouver des solutions alternatives aux r\u00e9actions du monde ext\u00e9rieur.<\/p>\n<h2><strong>Tenir la limite<\/strong><\/h2>\n<p>Lorsque le capitaine Picard interroge Kamala sur ses capacit\u00e9s empathiques et leur utilisation pour comprendre ses int\u00e9r\u00eats, elle avoue qu&rsquo;elle s&rsquo;est renseign\u00e9e sur lui. Parmi tous les hommes rencontr\u00e9s \u00e0 bord du vaisseau, c&rsquo;est le capitaine Picard qui a captiv\u00e9 son attention, notamment en son absence : lorsque Kamala est seule et libre de son adaptation naturelle. En un sens, il semble qu&rsquo;elle ait fait un choix semi-conscient de diriger ses facult\u00e9s vers lui.<\/p>\n<p>De la m\u00eame mani\u00e8re, les personnes en th\u00e9rapie peuvent choisir consciemment ou inconsciemment de concentrer leur amour et leurs facult\u00e9s sur nous, les th\u00e9rapeutes. Comme l&rsquo;a dit un de mes \u00e9tudiants : <strong>tout transfert est \u00e9rotique. C\u2019est toujours une question d\u2019amour.&nbsp;<br \/>\n<\/strong><\/p>\n<p>Nous pourrions nous interroger sur la part des sentiments exprim\u00e9s par notre patient \u00e0 notre \u00e9gard qui rel\u00e8ve du cadre s\u00e9curis\u00e9 de la relation th\u00e9rapeutique et de l&rsquo;espoir qu&rsquo;elle repr\u00e9sente, et quelle part, le cas \u00e9ch\u00e9ant, est attribuable \u00e0 notre \u00eatre r\u00e9el. Le premier ensemble de sentiments est g\u00e9n\u00e9ralement attribu\u00e9 au domaine du transfert\/contre-transfert, tandis que le second rel\u00e8ve de la relation r\u00e9elle dans le monde ext\u00e9rieur. Cependant, il est impossible de distinguer clairement les deux.<\/p>\n<p>Ces types de projections sont omnipr\u00e9sents dans toute relation, m\u00eame en dehors du cadre th\u00e9rapeutique. L&rsquo;\u00e9l\u00e9ment crucial dans la relation th\u00e9rapeutique r\u00e9side dans la promesse et l&rsquo;obligation \u00e9thique de placer le bien-\u00eatre de notre patient au premier plan. Cela signifie garder \u00e0 l&rsquo;esprit, avant tout, la part qui d\u00e9coule de la r\u00e9p\u00e9tition des sch\u00e9mas pass\u00e9s dans l&rsquo;histoire du patient, tout en maintenant une connexion avec nos patients dans <em>le ici et maintenant<\/em> du monde ext\u00e9rieur.<\/p>\n<p>Tout comme le capitaine Picard est enclin \u00e0 la promesse de gu\u00e9rir son c\u0153ur solitaire et meurtri par les mains et le corps emplis d&rsquo;amour de Kamala, nous pouvons aussi \u00eatre tent\u00e9s par nos patients. Les projections arch\u00e9typales peuvent aussi \u00eatre particuli\u00e8rement flatteuses.<\/p>\n<p>Cependant, \u00e0 l&rsquo;instar du Capitaine Picard, il est essentiel de trouver la force de r\u00e9sister sans rejeter. Dans une certaine mesure, nous devons canaliser et amplifier les qualit\u00e9s positives que nos patients nous transf\u00e8rent, tout en veillant \u00e0 ne pas nous identifier \u00e0 ces aspects.<\/p>\n<p>La raison pour laquelle Kamala est plus attir\u00e9e par le capitaine Picard que par tout autre est qu&rsquo;il d\u00e9gage le calme et la confiance. Au fond de lui, il sait qu&rsquo;il serait digne de son amour, qu&rsquo;il a quelque chose \u00e0 offrir et qu&rsquo;il pourrait lui plaire. Elle se sent en s\u00e9curit\u00e9 avec lui parce qu\u2019il ne souffre pas d&rsquo;ins\u00e9curit\u00e9 et n&rsquo;a pas besoin des autres pour se sentir entier. Il n&rsquo;a pas besoin de <em>se servir d&rsquo;<\/em>elle&nbsp;ou de la dominer. De plus, il a confiance en ses limites, ce qui fait qu&rsquo;il n&rsquo;a pas peur d&rsquo;elle. Il n&rsquo;adh\u00e8re pas au mythe masculin du f\u00e9minin de Rutter.<\/p>\n<p><strong>Bien que nous puissions parfois manquer de confiance dans le monde ext\u00e9rieur, en tant que th\u00e9rapeutes, il est essentiel de puiser dans notre \u00ab\u00a0capitaine Picard int\u00e9rieur\u00a0\u00bb pour incarner cette confiance profonde et cette estime de soi. Cela permet \u00e0 nos patients de voir et de sentir ce mod\u00e8le, les encourageant ainsi \u00e0 d\u00e9velopper ces qualit\u00e9s en eux-m\u00eames.<\/strong><\/p>\n<p>Kamala explique que ses pouvoirs empathiques peuvent d\u00e9tecter un homme de passion et de conviction, sans faille, ma\u00eetre de lui, et qu&rsquo;elle aimerait savoir ce qu&rsquo;il y a derri\u00e8re le mur. Le capitaine Picard ressent le danger imminent lorsqu&rsquo;elle atteint le c\u0153ur du sujet. C&rsquo;est un homme fier, solitaire et profond\u00e9ment marqu\u00e9 par son pass\u00e9, ce qui rend les paroles de Kamala d&rsquo;autant plus touchantes.<\/p>\n<p>En pla\u00e7ant son bien-\u00eatre avant le sien, il maintient une certaine distance et r\u00e9pond qu&rsquo;il n&rsquo;y a rien derri\u00e8re le mur, et qu&rsquo;il est un homme insipide. Elle le met en garde contre le fait de minimiser l&rsquo;int\u00e9r\u00eat qu&rsquo;une m\u00e9tamorphe le trouve int\u00e9ressant. Bien qu&rsquo;il en reconnaisse l&rsquo;importance, il ne s&rsquo;y abandonne pas. \u00ab\u00a0Je ne trouve pas cela anodin. Je m&rsquo;efforce de rester aussi insipide que possible.\u00a0\u00bb Malgr\u00e9 son insistance pour qu&rsquo;il lui rende visite, il refuse. Elle lui rappelle alors que m\u00eame les murs de J\u00e9richo sont tomb\u00e9s.<\/p>\n<p>De m\u00eame, nos patients peuvent ressentir une grande frustration si nous r\u00e9sistons trop ou si nous retenons trop de nous-m\u00eames trop longtemps.<\/p>\n<p>Lorsqu&rsquo;il lui demande pourquoi elle agit ainsi, elle affirme qu&rsquo;il ne peut y avoir qu&rsquo;une raison : \u00ab\u00a0une part de vous le veut\u00a0\u00bb. Elle a probablement raison.<\/p>\n<p><strong>De m\u00eame, il y a une part de v\u00e9rit\u00e9 lorsque nos patients per\u00e7oivent nos propres vuln\u00e9rabilit\u00e9s, ressentent intuitivement notre profond d\u00e9sir de gu\u00e9rison et pressentent qu&rsquo;une part de nous aspire \u00e0 leur amour et \u00e0 leur affection.<\/strong><\/p>\n<blockquote>\n<p>\u00ab\u00a0Ces femmes acceptent notre invitation \u00e0 d\u00e9voiler leur intimit\u00e9 : elles nous livrent des sensations longtemps cach\u00e9s, des r\u00eaves et des fantasmes. Ces sentiments, souvent m\u00eal\u00e9s \u00e0 des passions \u00e0 la fois claires et obscures, tourbillonnent autour de nous.<\/p>\n<p>Assez myst\u00e9rieusement, presque \u00e0 la mani\u00e8re d&rsquo;une induction \u00e9lectromagn\u00e9tique, nous, les hommes, ne pouvons nous emp\u00eacher, pouss\u00e9s par ce que les femmes nous font partager, de commencer \u00e0 \u00e9prouver quelques-unes de nos craintes longtemps ni\u00e9es, de nos blessures, de nos espoirs et de nos fantasmes.<\/p>\n<p>Tout comme la femme qui, dans une relation de confiance, peut rechercher chez l&rsquo;homme une r\u00e9ponse \u00e0 ce qui est bless\u00e9 ou frustr\u00e9 en elle, l&rsquo;homme peut commencer \u00e0 regarder la femme comme une source de gu\u00e9rison pour lui-m\u00eame.\u00a0\u00bb (Rutter 1989, p. 21-22)<\/p>\n<\/blockquote>\n<p>Comme un th\u00e9rapeute suffisamment bon, le capitaine Picard r\u00e9siste \u00e0 la tentation d&rsquo;accepter ce qui lui est offert. Il est profond\u00e9ment touch\u00e9, mais il pense \u00e0 son bien-\u00eatre ainsi qu&rsquo;au sien.<\/p>\n<p>Il est crucial de permettre \u00e0 nos patients de nous toucher \u00e9motionnellement et symboliquement. Aucun progr\u00e8s th\u00e9rapeutique significatif ne peut survenir si nous n&rsquo;investissons pas pleinement de nous-m\u00eames dans la relation th\u00e9rapeutique. Cependant, c\u00e9der au charme d&rsquo;un patient serait pr\u00e9judiciable, car cela violerait nos propres principes et valeurs.<\/p>\n<p>Le capitaine Picard sait que cela ne m\u00e8nera \u00e0 rien de bon. Il reconna\u00eet que les promesses de gain ne sont que des illusions, et que les cons\u00e9quences seraient trop graves. Comme dans toute relation en zone interdite, tomber amoureux de Kamala serait d\u00e9vastateur pour sa dignit\u00e9, sa r\u00e9putation, son estime de soi, voire sa carri\u00e8re.<\/p>\n<p>M\u00eame s&rsquo;il ne passe pas \u00e0 l&rsquo;acte, le simple fait de croire que Kamala pourrait combler sa vie et gu\u00e9rir ses blessures lui infligerait une douleur \u00e9ternelle<\/p>\n<p>Avouer son d\u00e9sir \u00e0 Kamala comporte le risque de l&rsquo;encourager, de devenir ainsi son amant fantomatique (<em>ghostly lover<\/em>), l&#8217;emp\u00eachant de suivre son propre chemin.<\/p>\n<p>Cela peut sembler cruel et insensible \u00e0 Kamala, voire m\u00eame malhonn\u00eate, mais le capitaine Picard r\u00e9siste dans l&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral. Kamala doit demeurer confin\u00e9e dans ses quartiers jusqu&rsquo;\u00e0 l&rsquo;arriv\u00e9e de son futur compagnon. Le capitaine Picard maintient ses distances et ne lui avoue jamais son d\u00e9sir.&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>CONIUNCTIO<\/strong><a id=\"coniunctio\"><\/a><\/h1>\n<h2><strong>Le Trickster au service du Soi<\/strong><\/h2>\n<p>Cependant, la vie \u0153uvre de mani\u00e8re myst\u00e9rieuse. Alors que les deux Ferengi rus\u00e9s tentent de corrompre l&rsquo;ambassadeur Kriosien pour obtenir Kamala, ce dernier est bless\u00e9 et tombe dans le coma, compromettant ainsi les n\u00e9gociations de paix et la c\u00e9r\u00e9monie de r\u00e9conciliation pr\u00e9vues deux jours plus tard. La p\u00e9riode de maturation sexuelle de Kamala touche \u00e0 sa fin et elle doit s&rsquo;unir \u00e0 son compagnon permanent dans les deux jours. Elle implore alors le capitaine Picard de remplacer l&rsquo;ambassadeur. Il consent une fois de plus dans l&rsquo;int\u00e9r\u00eat sup\u00e9rieur.<\/p>\n<p>Pour se pr\u00e9parer \u00e0 cet \u00e9v\u00e9nement, ils finissent par passer du temps ensemble. Un moment particuli\u00e8rement touchant survient lorsqu&rsquo;elle lui enseigne un chant de c\u00e9r\u00e9monie sur un xylophone traditionnel. C&rsquo;est \u00e0 ce moment-l\u00e0 qu&rsquo;il partage avec elle qu&rsquo;il jouait du piano et que cela faisait plaisir \u00e0 sa m\u00e8re.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24750\" src=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-music.png\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-music.png 600w, https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-music-300x225.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>La mention de sa m\u00e8re est d&rsquo;une grande signification. Dans la s\u00e9rie plus r\u00e9cente \u00ab\u00a0Star Trek : Picard\u00a0\u00bb (2021-2023), on d\u00e9couvre que la blessure profonde de son enfance est li\u00e9e \u00e0 la perte de sa m\u00e8re lorsqu&rsquo;il avait dix ans. Elle \u00e9tait une personne pleine de vie et d&rsquo;imagination, mais elle traversait \u00e9galement des p\u00e9riodes de profond trouble. M\u00eame s&rsquo;il a oubli\u00e9 certains d\u00e9tails, Picard porte le poids du regret pour son suicide. Cet \u00e9v\u00e9nement traumatisant a influenc\u00e9 sa d\u00e9cision de mener une vie dans les \u00e9toiles et a aliment\u00e9 ses h\u00e9sitations quant \u00e0 \u00e9tablir une relation amoureuse durable.<\/p>\n<h2><strong>Amiti\u00e9 symbolique<\/strong><\/h2>\n<p>Sentant toujours la r\u00e9sistance du capitaine Picard, Kamala boude et lui demande s&rsquo;il ne la trouve pas d\u00e9sirable. Sa r\u00e9ponse (dans la VO, et non VF) est magnifique : \u00ab\u00a0Je vous trouve indisponible.\u00a0\u00bb Elle s&rsquo;excuse pour sa question.<\/p>\n<p>\u00c0 ce stade, la tendresse dans les yeux et l&rsquo;expression de capitaine Picard est palpable. Gr\u00e2ce au leur collaboration, la confiance et l\u2019acceptation de qui est r\u00e9ellement l\u2019autre se sont d\u00e9velopp\u00e9es des deux c\u00f4t\u00e9s. Bien que Kamala retombe bri\u00e8vement dans le pi\u00e8ge de vouloir le s\u00e9duire, cette erreur est vite rectifi\u00e9e et le capitaine Picard accepte sa vraie nature.<\/p>\n<p><strong>Avec la confiance qui s&rsquo;est \u00e9tablie entre eux, il n&rsquo;a plus besoin de se d\u00e9fendre aussi vigoureusement contre ses avances. Il peut r\u00e9pondre honn\u00eatement, sans attitude d\u00e9fensive ni rejet.<\/strong><\/p>\n<p>Un r\u00e9sultat similaire est possible dans une analyse longue, surtout une fois que les projections personnelles sont largement \u00e9limin\u00e9es. Les auteurs jungiens \u00e9voquent alors le potentiel d&rsquo;une \u00ab\u00a0amiti\u00e9 symbolique\u00a0\u00bb (Henderson 1954, cit\u00e9 dans Wiener 2009, p. 25) ou d&rsquo;une \u00ab\u00a0v\u00e9ritable coniunctio\u00a0\u00bb (Kalsched 2014, p. 164).<\/p>\n<p>Kamala avoue que c&rsquo;est la toute premi\u00e8re fois de sa vie qu&rsquo;elle passe du temps seule, r\u00e9fl\u00e9chissant \u00e0 des questions curieuses sur son identit\u00e9 et ses d\u00e9sirs lorsque personne d&rsquo;autre n&rsquo;est pr\u00e9sent. La&nbsp;seule r\u00e9ponse qui lui vient est : \u00ab\u00a0Je suis \u00e0 vous, Alrik de Valt.\u00a0\u00bb Picard lui demande \u00e0 nouveau si elle le fait de son plein gr\u00e9. Elle r\u00e9pond que c&rsquo;est un bel honneur d&rsquo;avoir \u00e9t\u00e9 choisie par son peuple pour apporter la paix, mais qu&rsquo;elle trouve ironique de rencontrer un homme tel que Picard la veille de la c\u00e9r\u00e9monie.<\/p>\n<p>Leur conversation est interrompue par l&rsquo;arriv\u00e9e du chancelier Alrik. Lorsque le Capitaine Picard le rencontre, il est d\u00e9\u00e7u. Peu int\u00e9ress\u00e9 par <em>les sensibleries<\/em> ou par <em>la m\u00e9tamorphe<\/em>, il ne se soucie que des accords commerciaux.<\/p>\n<p>La soir\u00e9e pr\u00e9c\u00e9dant la c\u00e9r\u00e9monie, Kamala demande \u00e0 Picard de rester et de lui tenir compagnie car elle ne veut pas \u00eatre seule. Elle avoue qu&rsquo;elle aime le son de sa voix et propose d&rsquo;\u00e9teindre les lumi\u00e8res pour l&rsquo;\u00e9couter. Peut-\u00eatre \u00e0 cause de sa propre d\u00e9tresse int\u00e9rieure face \u00e0 l\u2019injustice d&rsquo;un mariage aussi malheureux, il accepte de rester. Cependant, il continue \u00e0 maintenir une certaine distance : \u00ab\u00a0laissez la lumi\u00e8re\u00a0\u00bb.<\/p>\n<p><strong>Afin de garantir un cadre th\u00e9rapeutique s\u00e9curis\u00e9, la relation doit demeurer dans la lumi\u00e8re de la conscience.<\/strong><\/p>\n<p>Elle lui demande s&rsquo;il consid\u00e8re qu&rsquo;elle est la forme de vie le plus exceptionnelle qu&rsquo;il ait jamais rencontr\u00e9e au cours de sa longue carri\u00e8re d&rsquo;exploration spatiale. Il acquiesce.<\/p>\n<p><strong>A ce stade du travail, il est important que les th\u00e9rapeutes se sentent libres d\u2019exprimer le fait qu&rsquo;un patient les touche, simplement et sans ambigu\u00eft\u00e9.<\/strong><\/p>\n<p>Dans un moment de tendresse, elle effleure son front. Il demande s&rsquo;il n&rsquo;a pas fait tout son possible pour \u00e9viter cela. Elle dit que c&rsquo;est peut-\u00eatre le plus s\u00fbr moyen de s\u00e9duire une m\u00e9tamorphe.<\/p>\n<blockquote>\n<p>Capitaine Picard : \u00ab\u00a0Je ne veux pas me servir de vous comme font les autres.\u00a0\u00bb<\/p>\n<p>Kamala : \u00ab\u00a0Mais vous n\u2019\u00eates pas comme eux. Jamais vous ne vous serviriez de moi. C&rsquo;est pourquoi je suis pr\u00e8s de vous cette nuit.\u00a0\u00bb<\/p>\n<\/blockquote>\n<p>La raison pour laquelle nos patients choisissent de nous aimer r\u00e9side dans le refuge que nous leur offrons. Pour beaucoup, c\u2019est une opportunit\u00e9 in\u00e9dite. Il est donc essentiel de maintenir des limites claires et de ne jamais utiliser notre position \u00e0 des fins personnelles. Le potentiel de gu\u00e9rison et de transformation s&rsquo;accompagne \u00e9galement du risque de revivre la premi\u00e8re blessure <em>(rewounding)<\/em><em>.<\/em><\/p>\n<h2><strong>L&rsquo;union transformatrice<\/strong><\/h2>\n<p>Le lendemain, peu avant la c\u00e9r\u00e9monie, Kamala explique au capitaine Picard qu&rsquo;il n&rsquo;y a pas de plus grand plaisir ni de plus grand d\u00e9sir pour une m\u00e9tamorphe que de se lier, \u00e0 la fin de son cycle de maturation, avec un homme avec qui elle peut faire monter son esprit et son c\u0153ur jusqu&rsquo;\u00e0 des sommets infinis, et de s&rsquo;entendre dire : \u00ab\u00a0En sa pr\u00e9sence, je sais que je m&rsquo;aime\u00a0\u00bb.<\/p>\n<p>Elle r\u00e9v\u00e8le qu&rsquo;elle s&rsquo;est attach\u00e9e \u00e0 lui et que ce qu&rsquo;elle est aujourd&rsquo;hui, elle le sera pour toujours. Choqu\u00e9 par cette r\u00e9v\u00e9lation, le capitaine Picard lui dit de renoncer \u00e0 la c\u00e9r\u00e9monie. Mais elle sait qu\u2019il ne fera jamais passer ses propres d\u00e9sirs \u00e9go\u00efstes avant les besoins du bien commun, et maintenant qu\u2019elle s\u2019est li\u00e9e \u00e0 lui, elle non plus ne le fera pas.<\/p>\n<p><strong>Avec le recul, on r\u00e9alise qu&rsquo;il s&rsquo;agissait d&rsquo;un choix conscient de sa part de se lier \u00e0 lui.<\/strong><\/p>\n<p>Sachant que son cycle de maturation sexuelle touchait \u00e0 sa fin, elle lui a demand\u00e9 de rester avec elle et lui a effleur\u00e9 le front. Nous pouvons imaginer que le moment ultime de mis en place du lien \u00e9motionnel s&rsquo;est produit \u00e0 ce moment-l\u00e0 : dans l&rsquo;instant tendre du toucher corporel.<\/p>\n<p>Peu importe l&rsquo;innocence du contact physique, cela a suffi pour sceller le destin. Elle a d\u00e9cid\u00e9 qu&rsquo;il \u00e9tait l&rsquo;\u00e9lu, et il l&rsquo;a laiss\u00e9 faire, tout en continuant \u00e0 sauvegarder les limites.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24752\" src=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-touch.png\" alt=\"\" width=\"600\" height=\"451\" srcset=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-touch.png 600w, https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2024\/05\/Star-Trek-TNG-The-Perfect-Mate-touch-300x226.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Kamala a ainsi fait le choix d\u2019\u00eatre la personne qu\u2019elle d\u00e9sirait vraiment \u00eatre. Elle aurait pu attendre de rencontrer son futur mari et s&rsquo;unir \u00e0 lui le lendemain matin. Cela aurait alt\u00e9r\u00e9 sa destin\u00e9e, la transformant en quelqu&rsquo;un d&rsquo;autre. Une voie plus ais\u00e9e peut-\u00eatre, mais une vie marqu\u00e9e par l&rsquo;inconscience. Au lieu de cela, elle a opt\u00e9 pour la conscience, la maturit\u00e9 et l&rsquo;individuation.<\/p>\n<p>En prenant l&rsquo;histoire au pied de la lettre, nous sommes constern\u00e9s \u00e0 l&rsquo;id\u00e9e qu&rsquo;elle doive d\u00e9sormais fa\u00e7onner sa vie pour un homme qui, selon nous, ne m\u00e9rite pas ses talents ni son amour. Beaucoup d&rsquo;entre nous esp\u00e8rent une fin hollywoodienne o\u00f9 le capitaine Picard, tel un chevalier, lui d\u00e9clare son amour et la lib\u00e8re de cette vie d&rsquo;oppression.<\/p>\n<p>La vraie maturation, cependant, est d&rsquo;une nature diff\u00e9rente. Consciente pleinement de sa propre nature int\u00e9rieure, elle a discern\u00e9 dans le capitaine Picard quelque chose qu&rsquo;elle souhaitait pour elle-m\u00eame.<\/p>\n<p><strong>Elle a choisi de s&rsquo;engager avec lui, et uniquement lui, et de devenir pour toujours une personne qu&rsquo;il puisse aimer. Mais seulement parce que c&rsquo;est le genre de personne qu&rsquo;elle aspire \u00e0 \u00eatre.<\/strong><\/p>\n<p>Elle n&rsquo;a poursuivi aucun des autres hommes qu&rsquo;elle a crois\u00e9s sur le vaisseau. Lui seul restait dans ses pens\u00e9es lorsqu&rsquo;elle \u00e9tait seule. Lui seul a relev\u00e9 le d\u00e9fi au lieu de l&rsquo;\u00e9viter. Il \u00e9tait le seul capable de r\u00e9sister \u00e0 l&rsquo;exploitation de Kamala pour son propre b\u00e9n\u00e9fice tout en permettant \u00e0 Kamala de le toucher profond\u00e9ment.<\/p>\n<p>C&rsquo;est une partie de la t\u00e2che que nous, th\u00e9rapeutes, devons accomplir pour nos patients. De plus, nous devons \u00e9galement laisser l&rsquo;histoire se d\u00e9rouler naturellement : nous devons faire preuve de patience et avoir confiance en la vie.<\/p>\n<p>Chaque fois que le Capitaine Picard s&rsquo;\u00e9loignait, la foi, la providence, ainsi qu&rsquo;une bonne dose d&rsquo;\u00e9nergie du Trickster, faisaient en sorte que, finalement, travailler pour le bien commun signifiait passer du temps \u00e0 collaborer \u00e9troitement avec elle : un temps durant lequel ils apprenaient \u00e0 se conna\u00eetre et formaient un attachement sain de l&rsquo;\u00e2me.<\/p>\n<p>Dans ses derniers mots, Kamala le rassure en affirmant qu&rsquo;elle demeure empathique et qu&rsquo;elle saura plaire au chancelier Alrik et assurer la paix entre les deux mondes m\u00eame sans lien avec lui. Elle est en paix avec son choix et avec qui elle est.<\/p>\n<p><strong>Elle a <em>amor fati <\/em>(amour du destin).<\/strong><\/p>\n<p>Elle ajoute en plaisantant qu&rsquo;elle esp\u00e8re qu&rsquo;il aime Shakespeare. Bien que son int\u00e9r\u00eat initial pour Shakespeare soit n\u00e9 de son d\u00e9sir de se lier au capitaine Picard, cet int\u00e9r\u00eat est d\u00e9sormais une partie int\u00e9grante de sa vie.<\/p>\n<p>Dans le cadre d&rsquo;une analyse approfondie et fructueuse, un ph\u00e9nom\u00e8ne similaire peut se produire.<\/p>\n<blockquote>\n<p>\u00ab\u00a0L&rsquo;analyste est g\u00e9n\u00e9riquement important en tant que constellateur de l&rsquo;atmosph\u00e8re dans laquelle l&rsquo;histoire [du patient] \u00e9merge, et en tant qu&rsquo;assistant dans la t\u00e2che de reconstruction et de compr\u00e9hension, mais il ou elle est particuli\u00e8rement important pour apporter les ingr\u00e9dients les plus personnels de cette autre psych\u00e9 dans l&rsquo;intimit\u00e9 de l&rsquo;analyse.\u00a0\u00bb (Stein 1987, p. 52)<\/p>\n<\/blockquote>\n<p>L&rsquo;histoire personnelle, la personnalit\u00e9 et les qualit\u00e9s de l&rsquo;analyste s&rsquo;int\u00e8grent d&rsquo;une mani\u00e8re ou d&rsquo;une autre dans la vie de l&rsquo;analysant. Ces influences ne se limitent pas seulement au pr\u00e9sent et \u00e0 l&rsquo;avenir du patient, mais affectent \u00e9galement son pass\u00e9. La fa\u00e7on dont l&rsquo;histoire personnelle d&rsquo;un patient est reconstruite au fil de l&rsquo;analyse, ainsi que sa personnalit\u00e9 et son r\u00e9cit, sont profond\u00e9ment influenc\u00e9es par celles du th\u00e9rapeute.<\/p>\n<p>On peut supposer que le processus est \u00e9galement r\u00e9ciproque. En tant que th\u00e9rapeutes, notre histoire de vie, tant pass\u00e9e que future, peut \u00e9galement \u00eatre profond\u00e9ment influenc\u00e9e par nos patients. Comme dans toute autre relation significative, nous sommes profond\u00e9ment transform\u00e9s par notre lien avec une autre personne.<\/p>\n<h2><strong>Les limites du lien th\u00e9rapeutique<\/strong><\/h2>\n<p>Pour Kamala, le capitaine Picard est son premier amour : sa premi\u00e8re romance qui lui apprend qui elle est et qui la pr\u00e9pare \u00e0 faire des choix sains dans toutes ses relations importantes ult\u00e9rieures. Dans le monde r\u00e9el, c\u2019est le r\u00f4le que nos figures parentales sont cens\u00e9es jouer.<\/p>\n<p>Lorsque ces premi\u00e8res relations sont malsaines, les gens peuvent devenir vuln\u00e9rables au risque d\u2019\u00eatre utilis\u00e9s et rejet\u00e9s.<\/p>\n<p><strong>Nos patients ont une seconde chance d&rsquo;avoir un premier amour sain avec un th\u00e9rapeute suffisamment bon qui comprend le potentiel ainsi que le risque de cette constellation particuli\u00e8re.<\/strong><\/p>\n<p>Il existe cependant des diff\u00e9rences importantes entre le lien parental et le lien th\u00e9rapeutique (ou autres relations en zone interdite).<\/p>\n<p>M\u00eame si tous les enfants doivent \u00e9ventuellement se s\u00e9parer de leurs figures parentales en termes de besoins primaires de d\u00e9pendance et d\u2019ind\u00e9pendance de pens\u00e9e et d\u2019action, les parents continuent id\u00e9alement d\u2019\u00eatre une source de soutien et d\u2019amour tout au long de la vie. La s\u00e9paration n\u2019est pas litt\u00e9rale et nette, mais symbolique et fluide.<\/p>\n<p>Un lien parent-enfant sain permet d&rsquo;alterner entre l&rsquo;ind\u00e9pendance et une d\u00e9pendance temporaire et partielle, surtout lorsque la vie les confronte \u00e0 des d\u00e9fis importants.<\/p>\n<p>M\u00eame si, en tant que th\u00e9rapeutes, nous continuons \u00e0 pr\u00e9server notre r\u00f4le apr\u00e8s la fin de la th\u00e9rapie et \u00e0 laisser la porte ouverte au retour des patients en cas de besoin, le seuil et l&rsquo;engagement de la reprise de la th\u00e9rapie sont bien plus \u00e9lev\u00e9s que ceux d&rsquo;appeler nos parents ou de les rencontrer pour prendre le th\u00e9. De m\u00eame, en tant que th\u00e9rapeutes, nous ne sommes tout simplement pas l\u00e0 pour surveiller que tout va bien avec nos anciens patients.<\/p>\n<p>\u00c0 la rigidit\u00e9 des limites et aux adieux stricts s\u2019ajoute le manque de relation corporelle. Bien qu\u2019une relation sexuelle soit \u00e9galement hors de question avec les parents, il existe de nombreuses autres fa\u00e7ons de se pr\u00e9occuper d&rsquo;autrui&nbsp;de mani\u00e8re incarn\u00e9e. Cela inclut non seulement l&rsquo;affection physique, mais aussi des actes simples comme partager un repas, aider \u00e0 un d\u00e9m\u00e9nagement, faire du babysitting, apporter un cadeau, remarquer une nouvelle coupe de cheveux. En bref : faire partie du quotidien incarn\u00e9 de chacun.<\/p>\n<p>Aucune de ces choses n\u2019est possible dans la relation th\u00e9rapeutique.<\/p>\n<p>Par cons\u00e9quent, il peut sembler particuli\u00e8rement cruel \u00e0 de nombreux patients de partager une intimit\u00e9 aussi incroyable avec un autre \u00eatre humain, de cr\u00e9er le lien sain le plus profond qu&rsquo;ils aient jamais eu, tout en ob\u00e9issant aux limites les plus strictes et avec pour seul r\u00e9sultat possible de dire au revoir.<\/p>\n<p><strong>En th\u00e9orie, les patients sont cens\u00e9s int\u00e9grer les qualit\u00e9s du lien et nouer une relation avec leurs figures int\u00e9rieures, de sorte que la pr\u00e9sence du th\u00e9rapeute en chair et en os n&rsquo;est plus n\u00e9cessaire.<\/strong><\/p>\n<p>Kamala a r\u00e9ussi. Cependant, nos patients ne sont pas des m\u00e9tamorphes empathiques : ce sont des individus dot\u00e9s de leurs propres d\u00e9sirs et aspirations. Se conformer aux attentes, m\u00eame de la part d&rsquo;un th\u00e9rapeute bien intentionn\u00e9 et convaincu de la l\u00e9gitimit\u00e9 de l&rsquo;objectif analytique, peut entra\u00eener un certain co\u00fbt.<\/p>\n<p>De plus, nos patients ne sont pas uniquement des \u00eatres psychiques et spirituels. Ce sont aussi des animaux \u00e0 sang chaud. Il est crucial de reconna\u00eetre le risque r\u00e9el que l&rsquo;analyse puisse devenir une forme de rejet du moi incarn\u00e9 du patient, et que la fin de l&rsquo;analyse puisse \u00e0 nouveau causer une blessure.<\/p>\n<h1 style=\"text-align: center;\"><strong>Le ROLE de la SOCIETE<\/strong><a id=\"society\"><\/a><\/h1>\n<p>Id\u00e9alement, la soci\u00e9t\u00e9 devrait mettre en place des structures ad\u00e9quates pour suppl\u00e9er aux lacunes parentales lorsque cela s&rsquo;av\u00e8re n\u00e9cessaire. Elle devrait \u00e9galement accorder une attention particuli\u00e8re \u00e0 la protection des individus vuln\u00e9rables contre l&rsquo;exploitation sexuelle, notamment \u00e0 un jeune \u00e2ge (au-del\u00e0 de l&rsquo;\u00e2ge de consentement, qui varie de 14 \u00e0 18 ans selon les pays) et\/ou dans des relations o\u00f9 un d\u00e9s\u00e9quilibre de pouvoir existe.<\/p>\n<p>Malheureusement, l&rsquo;\u00e9tablissement de r\u00e8gles plus strictes en mati\u00e8re de conduite sexuelle ne suffit pas. Ces r\u00e9glementations perdent leur sens lorsque les t\u00e9moins restent passifs face aux violations. Parfois, ces r\u00e8gles se retournent contre les victimes de l&rsquo;exploitation, car les gens les culpabilisent et bl\u00e2ment, par crainte des cons\u00e9quences, des r\u00e8gles qui sont cens\u00e9es assurer leur protection.<\/p>\n<p><strong>Ce qu&rsquo;il faut de toute urgence, c&rsquo;est une prise de conscience accrue de la dynamique et des dommages potentiels du comportement romantique et\/ou sexuel dans les relations en zone interdite.<\/strong><\/p>\n<p><strong>Une bonne mod\u00e9lisation est \u00e9galement essentielle.<\/strong><\/p>\n<p>En l&rsquo;absence de limites saines \u00e9tablies par nos propres parents et dans les relations ult\u00e9rieures, nous nous tournons vers la culture populaire pour trouver des indices sur la fa\u00e7on de penser et de se comporter. Et pourtant, la culture populaire a encore du chemin \u00e0 faire pour d\u00e9crire correctement la mani\u00e8re dont les th\u00e9rapeutes, les enseignants, etc., devraient se comporter avec les personnes dont ils ont la charge.<\/p>\n<p style=\"text-align: right;\"><em><a href=\"https:\/\/www.cgjung.net\/espace\/jps\/articles\/peggy-vermeesch\/perfect-mate\/\">Article original<\/a> <\/em><em>et traduction par Peggy Vermeesch.<\/em><\/p>\n<p style=\"text-align: right;\">Mai 2024<\/p>\n<p><em>Une version ult\u00e9rieure de ce travail, d\u00e9velopp\u00e9e dans un registre plus acad\u00e9mique et clinique, a \u00e9t\u00e9 pr\u00e9sent\u00e9e au Salon Jungien <a href=\"https:\/\/www.cgjung.net\/espace\/ressources\/medias\/#erotic-1\">(enregistrement vid\u00e9o)<\/a> et a \u00e9t\u00e9 accept\u00e9e pour publication dans le Journal of Analytical Psychology (JAP).<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Bibliographie<\/h2>\n<ul>\n<li><strong>Henderson<\/strong>, J.L. (1954) Resolution of the Transference in the Light of C. G. Jung\u2019s Psychology [R\u00e9solution du Transfert \u00e0 la Lumi\u00e8re de la Psychologie de C. G. Jung, article non traduit en fran\u00e7ais], cit\u00e9 dans Wiener 2009, p. 25.<\/li>\n<li><strong>Kalsched<\/strong>, D. (2014) The Inner World of Trauma : Archetypal Defenses of the Personal Spirit&nbsp;[Le Monde Int\u00e9rieur du Traumatisme : les D\u00e9fenses Arch\u00e9typales de l\u2019Esprit Personnel, livre non traduit en fran\u00e7ais].<\/li>\n<li><strong>Knobloch-Westerwick<\/strong>, S., Glynn, C.J., &amp; Huge, M. (2013). The Matilda Effect in Science Communication : An Experiment on Gender Bias in Publication Quality Perceptions and Collaboration Interest [L&rsquo;effet Matilda dans la communication scientifique : une exp\u00e9rience sur les pr\u00e9jug\u00e9s sexistes dans les perceptions de la qualit\u00e9 des publications et l&rsquo;int\u00e9r\u00eat pour la collaboration, article non traduit en fran\u00e7ais].<\/li>\n<li><strong>Rutter<\/strong>, P. (1989) Le Sexe Abusif [traduit de l&rsquo;anglais : Sex in the Forbidden Zone, litt\u00e9ralement : Le Sexe dans la Zone Interdite]<\/li>\n<li><strong>Stein<\/strong>, M. (1987). Looking Backward: Archetypes in Reconstruction [Regarder en Arri\u00e8re : les Arch\u00e9types dans la Reconstruction], dans Archetypal Process in Psychotherapy [Processus Arch\u00e9typal en Psychoth\u00e9rapie, livre non traduit en fran\u00e7ais]<\/li>\n<li><strong>Wiener<\/strong>, J. (2009) The Therapeutic Relationship : Transference, Countertransference, and the Making of Meaning [La Relation Th\u00e9rapeutique : Transfert, Contre-Transfert et Cr\u00e9ation de Sens, livre non traduit en fran\u00e7ais]<\/li>\n<\/ul>\n<p><em>Pour aller plus loin :<\/em><\/p>\n<ul>\n<li>Des articles, en lien avec Donald <strong>Kalsched<\/strong>, figurent dans les num\u00e9ros <a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/cahiers-jungiens-de-psychanalyse\/\">des cahiers jungiens de psychanalyse<\/a> :\n<ul>\n<li>117 (mars 2006) Figures miroir<\/li>\n<li>119-120 (octobre 2006) Le traumatisme dans l&rsquo;analyse<\/li>\n<li>123 (septembre 2007) Approcher l\u2019ombre<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cgjung.net\/contact.htm\"><strong>Adresser un message \u00e0 Peggy Vermeesch<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16462\" src=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2021\/05\/peggy-vermeesch-2.jpg\" alt=\"\" width=\"100\" height=\"126\" \/><\/h2>\n<h2>Peggy Vermeesch, PhD<\/h2>\n<p>Bas\u00e9e en France, Peggy Vermeesch est psychopraticienne psychodynamique jungienne et enseigne l&rsquo;<em>anglais pour psychologues<\/em> \u00e0 l&rsquo;Universit\u00e9 de Bretagne Occidentale. Titulaire d\u2019un doctorat en g\u00e9ophysique (Imperial College London), elle a \u00e9galement men\u00e9 une carri\u00e8re de chercheuse en g\u00e9ophysique \u00e0 l&rsquo;universit\u00e9 du Texas (\u00c9tats-Unis) et celle de Southampton (Royaume-Uni).<\/p>\n<p>Elle pr\u00e9sente lors de colloques internationaux, a \u00e9t\u00e9 invit\u00e9e au Salon jungien et publie dans des revues jungiennes. Contributrice au sein de l&rsquo;\u00e9quipe Espace Francophone Jungien (EFJ), elle est responsable de la ligne \u00e9ditoriale et de la coordination des contenus du site <a href=\"https:\/\/www.cgjung.net\/espace\/jps\/\" target=\"_blank\" rel=\"noopener\">Jungian Psychology Space (JPS)<\/a>, tout en d\u00e9veloppant les liens entre les mondes jungiens anglophone et francophone.<\/p>\n<p><a href=\"https:\/\/www.peggyvermeesch.com\/\" target=\"_blank\" rel=\"noopener\">En savoir plus sur Peggy Vermeesch<\/a><\/p>\n<h3>Articles<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/autre-programmable\/\">L&rsquo;Autre programmable : ambigu\u00eft\u00e9 ontologique des relations humain\u2013IA<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/parfaite-compagne\/\">Tenir la tension du transfert \u00e9rotique : incarner le Capitaine Picard dans \u00ab\u00a0La Parfaite Compagne\u00a0\u00bb de Star Trek<\/a>&nbsp;(\u00e9galement disponible en <a href=\"https:\/\/www.cgjung.net\/espace\/ressources\/medias\/#erotic-1\" rel=\"noopener\">vid\u00e9o<\/a> : version originale anglaise, sous-titr\u00e9 en fran\u00e7ais)<\/li>\n<li>L&rsquo;ombre et le mal dans Star Trek&nbsp;(\u00e9galement disponible en <a href=\"https:\/\/www.cgjung.net\/espace\/jps\/books-resources\/multimedia\/#startrek-1\" target=\"_blank\" rel=\"noopener\">vid\u00e9o<\/a> : version originale anglaise, sous-titr\u00e9 en fran\u00e7ais)&nbsp;:\n<ul>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/ombre-en-star-trek\/\">L\u2019inconscient collectif dans son aspect d\u2019ombre d\u00e9vorante et annihilante<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/ombre-collective\/\">Ombre collective et bouc \u00e9missaire : l\u2019essence du mal<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/transformation-ombre-collective\/\">Transformation de l\u2019ombre collective<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Le narcissisme illustr\u00e9 dans les contes tels que L\u2019Enfant de Marie, Blanche-Neige, et d&rsquo;autres :\n<ul>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/traumatismes-intergenerationnels\/\">La gu\u00e9rison des traumatismes pr\u00e9coces et des abus narcissiques<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/ombre-malefique\/\">Peut-on \u00eatre envahi par l\u2019ombre mal\u00e9fique d\u2019un autre ?<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/traumatisme-guerison\/\">Traumatisme interg\u00e9n\u00e9rationnel et gu\u00e9rison<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/formes-structurelles-psyche-feminine-toni-wolff\/\">Toni Wolff et ses formes structurelles de la psych\u00e9 f\u00e9minine<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/forces-archetypiques\/\">La n\u00e9cessit\u00e9 de reconna\u00eetre les forces arch\u00e9typiques<\/a><\/li>\n<\/ul>\n<h3>Entretiens<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/entretien-martin-schmidt\/\">Explorer le paradoxe dans le processus analytique<\/a>, entretien avec Martin Schmidt (\u00e9galement disponible en <a href=\"https:\/\/www.cgjung.net\/espace\/ressources\/medias\/#martin-1\" rel=\"noopener\">vid\u00e9o<\/a>&nbsp;: version originale anglaise, sous-titr\u00e9 en fran\u00e7ais)<\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/saisons-amour\/\">T\u00e9n\u00e8bres et lumi\u00e8re dans Les Saisons de l\u2019amour<\/a>, entretien avec Susan Tiberghien et Catherine Chevron-Tiberghien<\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/entretien-susan-schwartz\/\">Amour non partag\u00e9, blessure paternelle et fragilit\u00e9 du Soi<\/a>, entretien avec Susan Schwartz (\u00e9galement disponible en <a href=\"https:\/\/www.cgjung.net\/espace\/ressources\/medias\/#susan-1\" rel=\"noopener\">vid\u00e9o<\/a>&nbsp;: version originale anglaise, sous-titr\u00e9 en fran\u00e7ais)<\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/accueil\/peggy-vermeesch\/entretien-mark-saban\/\">Individuation de la psychologie analytique<\/a>, entretien avec Mark Saban<\/li>\n<\/ul>\n\n","protected":false},"excerpt":{"rendered":"<p>Peggy Vermeesch explore la mani\u00e8re dont un th\u00e9rapeute peut accompagner un patient dont la gu\u00e9rison et la transformation d\u00e9pendent de la possibilit\u00e9 de (re)vivre l&rsquo;exp\u00e9rience d&rsquo;un premier amour parental sain. Le mythe de Star Trek lui sert de fil conducteur. En plus de bonnes limites, il est crucial d&rsquo;appr\u00e9cier et d&rsquo;aimer v\u00e9ritablement nos patients lorsque [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":16720,"menu_order":35,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24424","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/24424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/comments?post=24424"}],"version-history":[{"count":134,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/24424\/revisions"}],"predecessor-version":[{"id":24827,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/24424\/revisions\/24827"}],"up":[{"embeddable":true,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/16720"}],"wp:attachment":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/media?parent=24424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}