{"id":2439,"date":"2016-10-26T15:17:35","date_gmt":"2016-10-26T13:17:35","guid":{"rendered":"https:\/\/www.cgjung.net\/espace\/?page_id=2439"},"modified":"2019-09-10T15:10:55","modified_gmt":"2019-09-10T13:10:55","slug":"plante-homeopathique-belladona-belladone","status":"publish","type":"page","link":"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/plante-belladona-belladone\/plante-homeopathique-belladona-belladone\/","title":{"rendered":"Belladona, un combat pour la vie"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Belladona est la plante hom\u00e9opathique qui symbolise un monde noir infernal et mortel et une bataille pour la lumi\u00e8re.<\/strong><\/p>\n<p style=\"text-align: right;\">Ce texte fait suite au texte <a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/plante-belladona-belladone\/\">Belladona, la belle qui a du chien.<\/a><\/p>\n<h2 style=\"text-align: justify;\">La propension au combat chez <em>Belladona<\/em><\/h2>\n<p style=\"text-align: justify;\">Chez <em>belladona<\/em>, le combat est un v\u00e9ritable leitmotiv. <em>Belladona<\/em> se sent poursuivi, veut fuir. <em>Belladona<\/em> est poursuivie en r\u00eave par un g\u00e9ant (comme <em>lycopodium<\/em>), c\u2019est-\u00e0-dire une force sup\u00e9rieure, un peu comme dans l\u2019histoire de David et de Goliath.<\/p>\n<p style=\"text-align: justify;\">Nombreux sont les contes, les l\u00e9gendes o\u00f9 il faut se battre non seulement contre un dragon, mais contre un g\u00e9ant, contre un ogre ou une ogresse<sup class='footnote'><a href='#fn-2439-1' id='fnref-2439-1' onclick='return fdfootnote_show(2439)'>1<\/a><\/sup>.<\/p>\n<p style=\"color: #ff6600; text-align: justify;\"><span style=\"color: #000000;\"><strong>Le h\u00e9ros doit combattre un \u00eatre fabuleux<\/strong> <sup class='footnote'><a href='#fn-2439-2' id='fnref-2439-2' onclick='return fdfootnote_show(2439)'>2<\/a><\/sup> pour d\u00e9livrer la belle et s\u2019unir avec son amour et atteindre de ce fait la jouissance du couple \u00e9lu, lib\u00e9r\u00e9 des scories infantiles. En fait, il s\u2019agit de livrer bataille \u00e0 une figure faisant obstacle \u00e0 cette union, une figure d\u2019amour d\u00e9voreuse, une force potentiellement n\u00e9gative dont il faut faire le sacrifice pour acc\u00e9der au bonheur et \u00e0 la pl\u00e9nitude.<\/span><\/p>\n<p style=\"text-align: justify;\">La propension au combat est certainement ambigu\u00eb chez <em>belladona<\/em>, car elle est combat pour la conqu\u00eate amoureuse mais aussi pour la suivie. <strong>Il y a s\u00e9duction et d\u00e9fense.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ce combat va s\u2019inscrire dans une foule de r\u00eaves, d\u2019impressions, de sensations, de pulsions et de marques physiques. Il r\u00eave d\u2019\u00eatre poursuivi, de meurtriers, de voleurs, de querelles, il a des sensations de battements, de lourdeur, d\u2019\u00e9clatement, de se briser, il est hypersensible \u00e0 l\u2019environnement, aux secousses, il est rouge, congestionn\u00e9. Il donne des coups de t\u00eate, c\u2019est un cabochard (<em>caput<\/em> en occitan). D\u2019ailleurs il est <strong>tr\u00e8s centr\u00e9 sur sa t\u00eate,<\/strong> qui est le si\u00e8ge de bien des tourments : Il prend froid par la t\u00eate, s\u2019il va chez le coiffeur, si elle est mouill\u00e9e. Il a la t\u00eate sensible au soleil, au point de craindre l\u2019insolation. Sa t\u00eate est congestionn\u00e9e, il l\u2019enfonce dans l\u2019oreiller, il a des mouvements de la t\u00eate, roule la t\u00eate. Il d\u00e9lire. Il voit des\u00a0 animaux qui le menacent. La vie est un amour, la vie est un combat\u2026<\/p>\n<p style=\"text-align: justify;\">La lutte de<em> belladona<\/em> se situe \u00e0 plusieurs niveaux, particuli\u00e8rement au niveau du sang, de la t\u00eate, de la gueule et des dents.<\/p>\n<h2 style=\"text-align: justify;\"><em>Belladona<\/em> est rouge sang<\/h2>\n<p style=\"text-align: justify;\">Le sang afflue chez <em>belladona<\/em>, de mani\u00e8re violente, pulsante, art\u00e9rielle. <strong>Le sujet a des pulsations fortes partout<\/strong> : palpitations au niveau du c\u0153ur, battements des vaisseaux, des carotides, de la t\u00eate\u2026 on est en pr\u00e9sence d\u2019une congestion sanguine, d\u2019une inflammation porteuse d\u2019hyperh\u00e9mie qui laissent le sujet cramoisi. Le pouls de <em>belladona<\/em>\u00a0 est plein, bondissant. Il pr\u00e9sente des h\u00e9morragies de sang rouge art\u00e9riel, jaillissant. Les r\u00e8gles sont abondantes, fr\u00e9quentes, chaudes. <em>Belladona<\/em> est sujet \u00e0 l\u2019insolation qui rend congestif, apoplectique et bouillant. <strong>Il est enclin aux \u00ab coups de sang \u00bb<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le sang est \u00e9videmment porteur de vie, mais aussi il est porteur d\u2019inflammation et de destruction. Il est li\u00e9 au Typhon Seth, qui, dans la m\u00e9decine \u00e9gyptienne ancienne, est un des facteurs pathog\u00e8nes de l\u2019individu malade car sa couleur est le rouge. Seth est le fr\u00e8re jaloux meurtrier d\u2019Osiris, nomm\u00e9 Typhon par Plutarque, qui en fait une sorte de diable.<\/p>\n<p style=\"text-align: justify;\"><strong>Le sang a un caract\u00e8re magique<\/strong>. Il fut utilis\u00e9 dans de nombreuses pratiques magiques. Il a \u00e9t\u00e9 \u00e0 l\u2019origine de l\u2019id\u00e9e du vampire qui a besoin de sang pour se nourrir et survivre. D\u2019ailleurs l\u2019ardeur, la vitalit\u00e9 d\u2019un \u00eatre le qualifie parfois de \u00ab\u00a0quelqu\u2019un qui a le sang chaud\u00a0\u00bb, par opposition au \u00ab sang de navet \u00bb. Il est le lien de c\u0153ur, le lien filial, le \u00ab lien de sang \u00bb, celui qui unit les \u00e2mes, les amiti\u00e9s, les amours, les g\u00e9n\u00e9rations. Il est le si\u00e8ge de la force vitale, de la chaleur vitale, de l\u2019\u00e2me.<\/p>\n<p style=\"text-align: justify;\">Chez les Grecs, le sang est associ\u00e9 au<em> thumos,<\/em> \u00e2me, principe de vie, principe de volont\u00e9, d\u2019intelligence, des sentiments aussi, c\u0153ur phr\u00e9nique de la sensibilit\u00e9 et du d\u00e9sir vital. Dans la Bible le sang a un caract\u00e8re sacr\u00e9. Il est d\u2019ailleurs interdit de manger le sang et la viande non saign\u00e9e de fa\u00e7on rituelle. Le sang n\u2019appartient qu\u2019\u00e0 Dieu. Il est dans la religion chr\u00e9tienne le pr\u00e9cieux sang vers\u00e9 par le Christ pour sauver le monde, le sang de l\u2019agneau vers\u00e9 pour laver les p\u00e9ch\u00e9s du monde. Il correspond au vin, le sang du Christ\u2026<\/p>\n<h2 style=\"text-align: justify;\">Se d\u00e9fendre en mordant<\/h2>\n<p style=\"text-align: justify;\">Dans cette confrontation avec une force d\u00e9voratrice, il faut r\u00e9sister. Il faut mordre aussi, il faut se h\u00e9risser, devenir \u00e9carlate, bondissant et gueulard.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9883 aligncenter\" src=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2019\/09\/atalante_fugitive.jpg\" alt=\"\" width=\"771\" height=\"738\" srcset=\"https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2019\/09\/atalante_fugitive.jpg 771w, https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2019\/09\/atalante_fugitive-300x287.jpg 300w, https:\/\/www.cgjung.net\/espace\/wp-content\/uploads\/2019\/09\/atalante_fugitive-768x735.jpg 768w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/p>\n<p style=\"text-align: justify;\">Le rebelle devient dragon, chien, loup, requin, crocodile, tigre, serpent fabuleux etc.. Du fait de son sang chaud (et aussi sans doute de l\u2019origine europ\u00e9enne occidentale de la plupart de nos pathog\u00e9n\u00e9sies classiques), <em>belladona<\/em> se projette particuli\u00e8rement sur <strong>l\u2019image du chien et du loup<\/strong>. Il est hant\u00e9 par la pr\u00e9sence de l\u2019image canine : il a peur des chien, a l\u2019impression de voir des chiens, se prend pour un chien, tousse comme un chien\u2026 Il cr\u00e9e toute une mythologie canine, se couvrant m\u00eame de poils en abondance. Il a parfois m\u00eame des poils sur le nez ! Il a une vie de chien !<\/p>\n<p style=\"text-align: justify;\">Dans l\u2019antiquit\u00e9, le chien \u00e9tait consid\u00e9r\u00e9 comme le garant de la vie \u00e9ternelle, comme Cerb\u00e8re. En Egypte, Anubis, \u00e0 t\u00eate de chacal est le psychopompe qui conduit au monde souterrain. Le chien est li\u00e9 au dieu Esculape en Gr\u00e8ce, il a souvent un lien tr\u00e8s positif avec l\u2019homme, il est ami, gardien et guide. Mais il pouvait aussi \u00eatre craint car on pr\u00e9tendait qu\u2019il pouvait apporter la maladie et la peste. <sup class='footnote'><a href='#fn-2439-3' id='fnref-2439-3' onclick='return fdfootnote_show(2439)'>3<\/a><\/sup><\/p>\n<p style=\"text-align: justify;\">Il existe dans <em>belladona<\/em> un <strong>fort climat animal<\/strong>. On rencontre dans <em>belladona,<\/em> qui appartient au domaine v\u00e9g\u00e9tal, des th\u00e8mes empreints d\u2019animalit\u00e9, de violence vitale, d\u2019\u00e9nergie mordante. Ceci a \u00e9t\u00e9 soulign\u00e9 par les anthroposophes. Il est en effet parfois difficile de classifier des individus selon le r\u00e8gne animal, v\u00e9g\u00e9tal ou min\u00e9ral. La nature est complexe, ses projections sont multiples et inconscientes.<\/p>\n<p style=\"text-align: justify;\">Dans le <strong>bestiaire alchimique et philosophique<\/strong>, la figure du chien d\u00e9vor\u00e9 par le loup repr\u00e9sente la purification de l&rsquo;or par l&rsquo;antimoine (loup gris). Le combat entre les deux \u00e9l\u00e9ments, \u00ab soufre et mercure \u00bb se trouve sans doute aussi dans des rem\u00e8des comme <em>stramonium, hyoscyamus, lyssinum<\/em> et m\u00eame <em>maiasaura lipidea,<\/em> (rem\u00e8de nouveau qui semble avoir une pathog\u00e9n\u00e9sie int\u00e9ressante) substances explosives o\u00f9 des fauves se battent et se confrontent avec violence.<\/p>\n<p style=\"text-align: justify;\"><em>Belladona<\/em>, rem\u00e8de compl\u00e9mentaire de <em>calcarea carbonica<\/em>, rem\u00e8de par excellence de la symbiose<sup class='footnote'><a href='#fn-2439-4' id='fnref-2439-4' onclick='return fdfootnote_show(2439)'>4<\/a><\/sup>,\u00a0 est caract\u00e9ris\u00e9 par deux tendances, une tendance s\u00e9ductrice accueillante aimable et une tendance d\u00e9fensive, agressive d\u00e9voratrice. Il peut \u00eatre gai, alerte, plaisant, tranquille, rigolard et m\u00eame compatissant. Il se sent entour\u00e9 d\u2019amis. Car il lui faut plaire, plaire \u00e0 cette entit\u00e9 puissante qui le tient bien serr\u00e9 dans son influence. Il s\u2019agit de ne pas d\u00e9plaire. Il faut \u00eatre agr\u00e9able, se rendre agr\u00e9able, agir, aider, se faire bien voir.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019\u00e9nergie de <em>belladona<\/em><\/strong>\u00a0 lui donne cet \u00e9lan, sinc\u00e8re, au milieu de son tumulte vital. Mais du fait de la peur de voir son espace s\u2019amenuiser, d\u2019\u00eatre rendu \u00e0 une peau de chagrin, il va devenir agressif, car il a lui m\u00eame peur d\u2019\u00eatre d\u00e9vor\u00e9. Il va se mettre \u00e0 montrer les dents et \u00e0 mordre. Le voici hant\u00e9 par les crocs et tout ce qui pourrait le happer, par tous les animaux \u00e0 m\u00e2choires impressionnantes, le chien, le loup, et autres bestioles \u00e0 la dent dure. C\u2019est le moment de la dentition chez le b\u00e9b\u00e9, o\u00f9 il va pouvoir mordre maman qui l\u2019\u00e9touffe un peu, dans une explosion f\u00e9brile torride, le visage en feu.<\/p>\n<h2 style=\"text-align: justify;\">Chaleur br\u00fblante<\/h2>\n<p style=\"text-align: justify;\">Nous abordons un autre th\u00e8me de <em>belladona<\/em>, celui de la chaleur br\u00fblante qui est le pendant du th\u00e8me du sang. <strong><em>Belladona<\/em> est un feu.<\/strong> Le rem\u00e8de est caract\u00e9ris\u00e9 par une v\u00e9ritable tendance \u00e0 irradier de la chaleur, comme une fournaise, \u00e0 tel point qu\u2019on a parfois le sentiment d\u2019\u00eatre en pr\u00e9sence d\u2019une source torride qu\u2019on peut percevoir \u00e0 l\u2019approche de la main.<\/p>\n<p style=\"text-align: justify;\">Cette \u00e9nergie irradiante est comme un soleil, mais ce n\u2019est pas celle du soleil<em> aurum,<\/em> fier de sa position alti\u00e8re centrale, mais elle est l\u2019\u00e9nergie qui chauffe sur son passage. Encore une fois, <strong>cette chaleur est double<\/strong>, car elle peut \u00eatre <strong>bienfaisante<\/strong> dans un premier temps, comme la ti\u00e9deur ut\u00e9rine o\u00f9 l\u2019enfant en symbiose a germ\u00e9, l\u2019\u00e9nergie qui donne la vie, mais dans un temps second, elle devient br\u00fblure et peut <strong>infliger la mort.<\/strong><\/p>\n<p style=\"text-align: justify;\">On trouve cette dualit\u00e9 de<em> Belladona<\/em> chez les<em> heruka<\/em> tib\u00e9tains, qui repr\u00e9sentent l\u2019aspect courrouc\u00e9 des d\u00e9it\u00e9s. Ce courroux peut para\u00eetre malfaisant, en fait il est parfois une juste col\u00e8re capable de pulv\u00e9riser les obstacles de la vie et les aspects sombres de la psych\u00e9. La col\u00e8re, l\u2019explosion de <em>belladona<\/em> peut \u00eatre d\u00e9l\u00e9t\u00e8re, mais il ne faut pas oublier qu\u2019elle est aussi justifi\u00e9e par la puissance de l\u2019\u00e9lan vital qui veut se sortir d\u2019une situation susceptible d\u2019emp\u00eacher l\u2019\u00e9volution positive d\u2019un \u00eatre en but \u00e0 ce qui voudrait l\u2019\u00e9touffer.<\/p>\n<p style=\"text-align: justify;\"><em>Belladona<\/em> d\u00e9gage une telle chaleur qu\u2019il craint le soleil<strong>,<\/strong> capable de lui infliger une insolation, capable de lui br\u00fbler la peau. Il craint le chaud qui augmente ses pulsations, qui le rend cramoisi. <strong>Le soleil a donn\u00e9 le nom de famille de <em>belladona<\/em><\/strong> : \u00ab solanac\u00e9e \u00bb<sup class='footnote'><a href='#fn-2439-5' id='fnref-2439-5' onclick='return fdfootnote_show(2439)'>5<\/a><\/sup>.<\/p>\n<p style=\"text-align: justify;\">Le soleil n\u2019est-il pas un des yeux d\u2019Horus, le dieu faucon ? Belladona\u00a0 a effectivement une <strong>relation \u00e9troite avec l\u2019\u0153il<\/strong>. Son nom, nous l\u2019avons dit, m\u00eame proviendrait du fait que les belles \u00e9largissaient leurs pupilles par un artifice atropinique d\u00fb \u00e0 la solanac\u00e9e. Sans doute avaient-elles une l\u00e9g\u00e8re photophobie, mais, comme elles craignaient le soleil (les \u00ab belles dames \u00bb de l\u2019\u00e9poque \u00e9taient des cr\u00e9atures de l\u2018ombre), elles n\u2019en souffraient pas trop. De plus, elles avaient le regard immense et velout\u00e9 apte \u00e0 la s\u00e9duction. Car <em>belladona<\/em> n\u2019est pas forc\u00e9ment une brute, c\u2019est aussi possiblement la douceur envo\u00fbtante d\u2019un \u00eatre qui veut d\u00e9sarmer l\u2019adversaire par son charme, d\u2019autant plus qu\u2019il a une solide libido.<\/p>\n<p style=\"text-align: justify;\">Qui dit soleil, dit chaleur, mais aussi clart\u00e9, lumi\u00e8re.<em> Belladona<\/em> craint la lumi\u00e8re du fait de sa mydriase. La grande clart\u00e9 le g\u00e8ne, surtout lorsqu\u2019il souffre de la t\u00eate. La migraine pulsante en est aggrav\u00e9e chez lui et il pr\u00e9f\u00e8re tirer les rideaux ou fermer les volets. <strong>La lumi\u00e8re lui fait ma<\/strong>l, mais aussi le bruit, la moindre agression, le moindre choc qui la fait sursauter.<\/p>\n<p style=\"text-align: justify;\">Tous ces th\u00e8mes li\u00e9s \u00e0 la lumi\u00e8re, \u00e0 la chaleur, soulignent la pr\u00e9sence en lui d\u2019un feu vital intense, d\u2019une nature chaude et s\u00e8che comme le feu, \u00e0 tel point qu\u2019il a peur de l\u2019eau qui pourrait lui \u00eatre contraire.<\/p>\n<p style=\"text-align: justify;\">Belladona\u00a0 est bouillant et ardent. C\u2019est v\u00e9ritablement un dragon capable de cracher le feu. C\u2019est une \u00e9nergie chaude et combative.<\/p>\n<h2 style=\"text-align: justify;\">Un monde noir infernal et mortel<\/h2>\n<p style=\"text-align: justify;\">Face \u00e0 la d\u00e9voration du dragon <em>belladona<\/em> se situe un monde noir infernal et mortel : le dragon garde le monde de la grotte, un monde chtonien qui communique avec les ombres. Son aversion pour la lumi\u00e8re la rapproche d\u2019un univers sombre et noir qu\u2019il redoute (mais il peut \u00e9galement d\u00e9sirer la lumi\u00e8re). Belladona voit des animaux, des animaux noirs (chiens et chats) ou fonc\u00e9s.<\/p>\n<p style=\"text-align: justify;\"><em>Belladona<\/em> peut avoir <strong>peur de ce monde inconscient<\/strong> qui l\u2019envahit et a peur du noir. Le chien noir est une image d\u2019Anubis, ce chacal de la famille des canid\u00e9s qui se nourrit volontiers de charognes et qui est consacr\u00e9 en Egypte aux rites fun\u00e9raires. Il poss\u00e8de la t\u00eate d\u2019un chien sauvage sur un corps humain. Il participe \u00e0 part enti\u00e8re \u00e0 l\u2019activit\u00e9 d\u2019Atropos puisqu\u2019il prend part \u00e0 la psychostasie. Comme tous ceux qui sont impliqu\u00e9s dans un r\u00f4le osiriaque, il participe de l\u2019univers lunaire (L\u2019autre \u0153il d\u2019Horus.), \u00e0 tel point qu\u2019il peut subir une aggravation \u00e0 la pleine lune et m\u00eame convulser \u00e0 cette p\u00e9riode. On retrouve dans les Enfers grecs le chien Cerb\u00e8re \u00e0 trois t\u00eates qui en garde l\u2019entr\u00e9e et terrorise ceux qui doivent s\u2019y rendre.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Belladona<\/em> a un aspect d\u00e9moniaque<\/strong>. Des chiens noirs sont parfois les compagnons des sorciers. Cet aspect d\u00e9moniaque n\u2019est pas forc\u00e9ment n\u00e9gatif (c\u2019est la m\u00eame chose pour <em>phosphorus<\/em>) car le d\u00e9mon est garant d\u2019une \u00e9nergie chtonienne primitive (qui certes peut inqui\u00e9ter, surtout pour le christianisme) ; elle est l\u2019ombre qui relie \u00e0 la terre, aux origines et \u00e0 la force vitale.<\/p>\n<p style=\"text-align: justify;\">Belladona\u00a0 a <strong>l\u2019illusion de voir le diable<\/strong> (qui dans le Faust de Goethe appara\u00eet sous la forme d\u2019un chien barbet) et celle d\u2019<strong>\u00eatre pris par le diable<\/strong> ; il se sent sans doute coupable, il est poursuivi par les fantasmes animaux de son inconscient. <em>Belladona<\/em> est une sorte de <strong><em>Faust<\/em><\/strong>, de <em>sulfur\u00a0<\/em> faustien qui voit des diables, qui vend son \u00e2me au diable pour jouir du monde et de la connaissance, mais son probl\u00e8me n\u2019est ni de savoir, ni de philosopher, mais d\u2019\u00eatre confront\u00e9 \u00e0 l\u2019\u00e9nergie primordiale de la vie qui pourrait lui \u00eatre refus\u00e9e et \u00e0 laquelle il a droit d\u2019acc\u00e9der.<\/p>\n<p style=\"text-align: justify;\">Le combat auquel <em>belladona<\/em> se livre, cette lutte entre l\u2019ombre et la lumi\u00e8re solaire (solanac\u00e9es et Nachtschattengew\u00e4chse), est un combat de titans, sulfureux et enflamm\u00e9 o\u00f9 <strong>le sujet d\u00e9lire.<\/strong> Il y voit des fant\u00f4mes, des ombres, de sombres animaux mena\u00e7ants et dent\u00e9s. Il est pris dans une sorte de g\u00e9henne torride, sursaute, crie et se d\u00e9bat dans un cauchemar de type <em>delirium tremens<\/em>. Il est entre la vie qu\u2019il d\u00e9sire (car son \u00e9nergie est grande) et la mort qu\u2019il entrevoit si il ne vainc pas le dragon qui lui fait obstacle.<\/p>\n<p style=\"text-align: justify;\">Cette lutte entre la vie lumineuse et la mort nocturne est symbolis\u00e9e par la rivalit\u00e9 quotidienne du soleil menac\u00e9 d\u2019\u00eatre absorb\u00e9 chaque nuit par le serpent dragon Ap\u00f4pis. R\u00ea sur sa barque est menac\u00e9 chaque jour d\u2019\u00eatre englouti par l\u2019abominable Ap\u00f4pis.<\/p>\n<p style=\"text-align: justify;\">On\u00a0 doit remarquer que <em>belladona<\/em> a<strong> peur des serpents<\/strong> et a l\u2019illusion de voir des serpents. Les humains prient et supplient le soleil de revenir au matin car sans lui la vie, la lumi\u00e8re, l\u2019intelligence et la clart\u00e9 de l\u2019esprit ne seraient plus qu\u2019un chaos et une obscurit\u00e9 sans fond. L\u2019humanit\u00e9 a peur de cet engloutissement qui n\u2019aurait que la barbarie et la mort pour r\u00e9sultat.<\/p>\n<p style=\"text-align: justify;\"><strong>Car le combat de belladona est bien un combat pour la vie, qu\u2019il s\u2019agisse du moment magnifique mais douloureux de la naissance (entre deux mondes, v\u00e9ritable bardo), du moment de la dentition o\u00f9 l\u2019enfant sort de la d\u00e9licieuse et contraignante \u00e9treinte de la m\u00e8re, o\u00f9 du d\u00e9lire morbide du patient entre deux \u00e9tats de conscience. Ce combat est une bataille pour la lumi\u00e8re, pour la vue, pour la vision large, celle d\u2019un \u0153il \u00e0 la pupille large, comme l\u2019\u0153il d\u2019Horus, vengeur d\u2019Osiris vainqueur de la mort, et triomphateur de Seth, le typhon d\u00e9moniaque.<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>Important<\/strong> : il est possible que l&rsquo;un des rem\u00e8des d\u00e9crits sur ce site vous convienne, mais on ne peut l&rsquo;affirmer sans un interrogatoire et un examen s\u00e9rieux effectu\u00e9s par un m\u00e9decin hom\u00e9opathe. Le site est fait pour faire conna\u00eetre l&rsquo;hom\u00e9opathie, en aucun cas il ne peut se substituer \u00e0 un th\u00e9rapeute. Le docteur Bernard Long n&rsquo;assure plus de consultations.<\/em><\/p>\n<p><a href=\"https:\/\/www.cgjung.net\/contact.htm\"><strong>Adresser un message \u00e0 Bernard Long<\/strong><\/a>&nbsp;<span style=\"color: #ff0000;\">(Il ne doit pas concerner une consultation \u00e0 caract\u00e8re m\u00e9dical).<\/span><\/p>\n<h2>Bernard Long<\/h2>\n<p><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/\">Pr\u00e9sentation du docteur Bernard Long<\/a><\/p>\n<h2>Ouvrages<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/symboles-archetypes\/\">Symboles et arch\u00e9types en hom\u00e9opathie<\/a>, reprend un certain nombre d\u2019articles publi\u00e9s sur ce site et les compl\u00e8te.<\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/symboles-archetypes\/#repertoire\">Le R\u00e9pertoire hom\u00e9opathique des maladies aigu\u00ebs<\/a> compl\u00e8te utilement cet ouvrage.<\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/enfant-mere-homeopathie\/\">L&rsquo;enfant, la m\u00e8re et l&rsquo;hom\u00e9opathie<\/a><\/li>\n<\/ul>\n<h2>Articles de Bernard Long<\/h2>\n<div class=\"menu-bernard-long-container\">\n<ul id=\"menu-bernard-long\" class=\"menu\">\n<li id=\"menu-item-2211\" class=\"menu-item menu-item-type-post_type menu-item-object-page current-page-ancestor menu-item-2211\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/lexique-de-lhomeopathie\/\">Lexique de l\u2019hom\u00e9opathie<\/a><\/li>\n<li id=\"menu-item-3010\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3010\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/homeopathie-et-synchronicite\/\">Hom\u00e9opathie et synchronicit\u00e9<\/a><\/li>\n<li id=\"menu-item-2212\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2212\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/le-reve-en-pratique-homeopathique\/\">R\u00eave en hom\u00e9opathie<\/a><\/li>\n<li id=\"menu-item-2213\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2213\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/homeopathie-mandala\/\">Hom\u00e9opathie et mandala<\/a><\/li>\n<li id=\"menu-item-2214\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2214\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/le-mercure\/\">Le Mercure<\/a><\/li>\n<li id=\"menu-item-2215\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2215\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/coquille-philosophique\/\">Calcarea carbonica<\/a><\/li>\n<li id=\"menu-item-2216\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2216\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/pulsatilla\/\">Pulsatilla<\/a><\/li>\n<li id=\"menu-item-2217\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2217\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/jung-et-lhomeopathie\/\">Jung et l\u2019hom\u00e9opathie<\/a><\/li>\n<li id=\"menu-item-2218\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2218\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/aconit\/\">Aconit<\/a><\/li>\n<li id=\"menu-item-2257\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2257\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/arsenic\/\">Arsenic : aspects philosophique et psychologique<\/a><\/li>\n<li id=\"menu-item-2219\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2219\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/arsenic\/vie-maladie-mortelle\/\">Arsenic : la vie est une maladie mortelle<\/a><\/li>\n<li id=\"menu-item-2220\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2220\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/plante-belladona-belladone\/\">Belladona, la belle qui a du chien<\/a><\/li>\n<li id=\"menu-item-2446\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2446\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/plante-belladona-belladone\/plante-homeopathique-belladona-belladone\/\">Belladona, un combat pour la vie<\/a><\/li>\n<li id=\"menu-item-3433\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3433\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/information-compensatoire\/\">Hom\u00e9opathie : information compensatoire ?<\/a><\/li>\n<li id=\"menu-item-4301\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4301\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/alumine-matiere-alchimie-symbolique\/\">D\u2019alumine \u00e0 alumina : mati\u00e8re, alchimie, symbolique<\/a><\/li>\n<li id=\"menu-item-5163\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5163\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/symbolisme-du-sel\/\">Symbolisme du sel et hom\u00e9opathie<\/a><\/li>\n<li id=\"menu-item-5686\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5686\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/ambre-gris\/\">L\u2019ambre gris, ambra grisea<\/a><\/li>\n<li id=\"menu-item-6253\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6253\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/de-soleil-dor-aurum-metallicum\/\">De soleil et d\u2019or : aurum m\u00e9tallicum<\/a><\/li>\n<li id=\"menu-item-6699\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6699\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/argent-argentum\/\">Lune d\u2019argent : argentum<\/a><\/li>\n<li id=\"menu-item-7142\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7142\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/le-charbon-de-bois-carbo-vegetabilis\/\">Le charbon de bois : carbo vegetabilis<\/a><\/li>\n<li id=\"menu-item-7203\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7203\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/cuivre-et-remede\/\">Cuivre et rem\u00e8de \u2013 Cuprum metallicum<\/a><\/li>\n<li id=\"menu-item-7266\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7266\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/symptomes-symboles\/\">Sympt\u00f4mes et Symboles en hom\u00e9opathie<\/a><\/li>\n<li id=\"menu-item-7975\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7975\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/soufre-sulfur\/\">Le soufre, sulfur<\/a><\/li>\n<li id=\"menu-item-8444\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8444\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/serpent-lachesis-mutus\/\">Le serpent : Lachesis mutus<\/a><\/li>\n<li id=\"menu-item-8857\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8857\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/la-belle-et-le-crapaud\/\">La belle et le crapaud<\/a><\/li>\n<li id=\"menu-item-9847\" class=\"menu-item menu-item-type- menu-item-object- menu-item-9847\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/lycopodium\/\">Au loup ! Le rem\u00e8de hom\u00e9opathique lycopodium clavatum<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/le-plomb-plumbum-metallicum\/\">Le plomb, plumbum m\u00e9tallicum hom\u00e9opathique<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/camomille-remede\/\">La camomille : le rem\u00e8de hom\u00e9opathique chamomilla<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/bore-borax\/\">Le bore, borax, rem\u00e8de hom\u00e9opathique<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/rhus-toxicodendron\/\">Rhus toxicodendron, le rem\u00e8de et le sujet<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/bryonia-alba-le-remede-du-confine\/\">Bryonia alba le rem\u00e8de du confin\u00e9<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/staphysagria-remede-pouilleux\/\">Staphysagria le rem\u00e8de du pouilleux<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/veratrum-album-remede-vantard\/\">Veratrum album, rem\u00e8de pr\u00e9tentieux et vantard<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/hepar-sulfur-calcareum-un-pyromane-frileux\/\">Hepar Sulfur Calcareum, un pyromane frileux<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/sepia-sang-encre\/\">Le sujet sepia se fait un sang d\u2019encre<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/zincum-metallicum\/\">Zincum metallicum&nbsp;un sujet galvanis\u00e9<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/natrum-carbonicum-lessive-alchimique\/\">Natrum carbonicum : la grande lessive alchimique<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/silicea\/\">Silicea sent le sol se d\u00e9rober sous ses pieds<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/hyoscyamus-niger\/\">La jusquiame noire, hyoscyamus niger, au pays des sorci\u00e8res<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/ammonium-muriaticum\/\">Ammonium muriaticum et l&rsquo;histoire du Petit Poucet<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/capsicum-annuum\/\">La nostalgie du pays de Capsicum annuum<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/kalium-carbonicum\/\">Kalium carbonicum, purification et destruction<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/causticum-caustique\/\">Causticum : un \u00eatre caustique et empathique<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/thuya-occidentalis\/\">Thuya occidentalis et le mythe d\u2019osiris<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/anacardium-orientale-ange-ou-demon\/\">Anacardium orientale, ange ou d\u00e9mon ?<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/china-officinalis\/\">China officinalis, Hahnemann et les d\u00e9buts de l\u2019hom\u00e9opathie<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/ignatia-amara-est-fou-damour\/\">Ignatia amara est fou d\u2019amour<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/nux-vomica\/\">Nux vomica, le juste milieu entre l\u2019abus et la rigueur<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/ombre-lumiere\/\">Datura Stramonium, ombre, lumi\u00e8re, symbiose et magie<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/alchimie-homeopathie\/\">Le cinabre : alchimie et hom\u00e9opathie<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/cicuta-virosa\/\">Cicuta virosa, une ombellif\u00e8re infantile<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/tuberculinum\/\">Tuberculinum, un rem\u00e8de pneumatique<\/a><\/li>\n<li><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/camphora\/\">Camphora &#8211; La solitude de ces espaces infinis me glace !<\/a><\/li>\n<li id=\"menu-item-3149\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3149\"><a href=\"https:\/\/www.cgjung.net\/espace\/bernard-long-homeopathie\/poesies-de-bernard-long\/\">Po\u00e9sies de Bernard Long<\/a><\/li>\n<\/ul>\n<\/div>\n\n<p><strong>Notes :<\/strong><\/p>\n<div class='footnotes' id='footnotes-2439'>\n<div class='footnotedivider'><\/div>\n<ol>\n<li id='fn-2439-1'> Ainsi le conte\u00a0 de Hansel et Gretel avec la sorci\u00e8re qui veut manger les enfants ou le conte\u00a0 de la comtesse Bray\u00e8re qui d\u00e9vorait les petits enfants dans la r\u00e9gion du Puy-de-Chanat (Puy-de-D\u00f4me). <span class='footnotereverse'><a href='#fnref-2439-1'>&#8617;<\/a><\/span><\/li>\n<li id='fn-2439-2'> Nicolas Flamel a repr\u00e9sent\u00e9 la \u00ab premi\u00e8re mati\u00e8re \u00bb dans ses figures hi\u00e9roglyphiques sous la figure de deux Dragons, l\u2019un ail\u00e9, l\u2019autre sans ailes, pour signifier, dit-il \u00ab le principe fixe, ou le m\u00e2le, ou le soufre ; &amp; par celui qui a des ailes, le principe volatil, ou l\u2019humidit\u00e9, ou la femelle, ou l\u2019argent-vif. Ce sont, ajoute-t-il, le Soleil &amp; la Lune de source mercurielle. Ce sont ces Serpents &amp; Dragons que les anciens Egyptiens ont peints en cercle, \u00e0 la t\u00eate mordant, la queue, pour dire qu\u2019ils \u00e9taient sortis d\u2019une m\u00eame chose, &amp; qu\u2019elle seule \u00e9tait suffisante \u00e0 elle-m\u00eame, &amp; qu\u2019en son contour &amp; circulation elle se parfaisait. Ce font ces Dragons que les anciens Philosophes Po\u00e8tes ont mis \u00e0 garder sans dormir les pommes dor\u00e9es des jardins des Vierges Hesp\u00e9rides. Ce sont ceux sur lesquels Jason, en l\u2019aventure de la Toison d\u2019or, versa le jus pr\u00e9par\u00e9 par la belle M\u00e9d\u00e9e ; des discours desquels les livres des Philosophes sont si remplis, qu\u2019il n\u2019y a point de Philosophe qui n\u2019en ait \u00e9crit depuis le v\u00e9ridique Herm\u00e8s Trim\u00e9giste, Orph\u00e9e, Pythagoras, Art\u00e9phius, Morienus &amp; les autres suivants jusqu\u2019\u00e0 moi. \u00bb. <span class='footnotereverse'><a href='#fnref-2439-2'>&#8617;<\/a><\/span><\/li>\n<li id='fn-2439-3'> Marie Louise\u00a0von Franz. Interpr\u00e9tation des contes de f\u00e9es. Paris : ed. Jacqueline Renard ; 1993. p. 158. <span class='footnotereverse'><a href='#fnref-2439-3'>&#8617;<\/a><\/span><\/li>\n<li id='fn-2439-4'> cf. note 6 ci-dessus. <span class='footnotereverse'><a href='#fnref-2439-4'>&#8617;<\/a><\/span><\/li>\n<li id='fn-2439-5'> Solanac\u00e9es : leur appellation germano-celtique nah-skado ferait allusion \u00e0 des esprits nocturnes et nuisibles. L\u2019allemand conna\u00eet le mot Nachtschatten (ombre de nuit) pour d\u00e9signer les solanac\u00e9es. Le fran\u00e7ais d\u00e9signe au contraire la famille de ces plantes par le mot \u00ab solanac\u00e9e \u00bb et l\u2019ordre qui les englobe par le mot \u00ab solanale\u00bb, termes d\u00e9riv\u00e9s de sol, le \u00ab soleil \u00bb. <span class='footnotereverse'><a href='#fnref-2439-5'>&#8617;<\/a><\/span><\/li>\n<\/ol>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Belladona est la plante hom\u00e9opathique qui symbolise un monde noir infernal et mortel et une bataille pour la lumi\u00e8re. Ce texte fait suite au texte Belladona, la belle qui a du chien. La propension au combat chez Belladona Chez belladona, le combat est un v\u00e9ritable leitmotiv. Belladona se sent poursuivi, veut fuir. Belladona est poursuivie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1830,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2439","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/2439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/comments?post=2439"}],"version-history":[{"count":8,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/2439\/revisions"}],"predecessor-version":[{"id":9885,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/2439\/revisions\/9885"}],"up":[{"embeddable":true,"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/pages\/1830"}],"wp:attachment":[{"href":"https:\/\/www.cgjung.net\/espace\/wp-json\/wp\/v2\/media?parent=2439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}